{"id":2628,"date":"2017-11-17T17:05:19","date_gmt":"2017-11-17T16:05:19","guid":{"rendered":"https:\/\/sboverseas.org\/?p=2628"},"modified":"2017-11-17T17:05:19","modified_gmt":"2017-11-17T16:05:19","slug":"leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens","status":"publish","type":"post","link":"https:\/\/sboverseas.org\/nl\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/","title":{"rendered":"L\u2019Education en Turquie inaccessible \u00e0 des milliers d\u2019enfants r\u00e9fugi\u00e9s Syriens"},"content":{"rendered":"<p>Selon le dernier rapport du HCR, \u00ab&nbsp;Global Trends, Forced Displacement&nbsp;\u00bb, fin 2016, 65,5 millions de personnes avaient \u00e9t\u00e9 d\u00e9plac\u00e9es \u00e0 cause des pers\u00e9cutions subies, des conflits, des violences ou des violations des Droits de l\u2019Homme.<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a> Parmis ces 65,5 millions de personnes d\u00e9plac\u00e9es, 22,5 sont enregistr\u00e9es comme r\u00e9fugi\u00e9s.<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a> Aujourd\u2019hui, Portail Interagence de partage de l&#8217;Information indique que 5&nbsp;344&nbsp;184 personnes sont enregistr\u00e9es comme r\u00e9fugi\u00e9 syrien.<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a> Le nombre de r\u00e9fugi\u00e9s syriens en Turquie devient alors, sur base de ces chiffres, tr\u00e8s inqui\u00e9tant.<\/p>\n<p>En effet, au 5 novembre 2017, ce nombre atteignait 3,28 millions.<a href=\"#_ftn4\" name=\"_ftnref4\">[4]<\/a> Il faut noter que c\u2019est la troisi\u00e8me ann\u00e9e cons\u00e9cutive que le HCR a d\u00e9sign\u00e9 la Turquie comme le pays accueillant le plus de r\u00e9fugi\u00e9s.<a href=\"#_ftn5\" name=\"_ftnref5\">[5]<\/a> En effet, le ratio de r\u00e9fugi\u00e9 syrien en Turquie est de 1 pour 24 citoyens turcs.<a href=\"#_ftn6\" name=\"_ftnref6\">[6]<\/a> A titre de comparaison, en Europe, ce ratio est de 1&nbsp;pour 508.<a href=\"#_ftn7\" name=\"_ftnref7\">[7]<\/a> De plus, les importants flux migratoire que nous observons ces derni\u00e8res ann\u00e9es font chaque jour \u00e9voluer ces chiffres. Face \u00e0 leur ampleur, la Turquie s\u2019est trouv\u00e9e dans une situation \u00e0 laquelle elle n\u2019\u00e9tait pas pr\u00e9par\u00e9e ni du point de vue administratif, ni du point de vu logistique.<\/p>\n<p>C\u2019est dans ce contexte qu\u2019a \u00e9t\u00e9 adopt\u00e9 l\u2019Accord sur l&#8217;immigration entre la Turquie et l&#8217;Union europ\u00e9enne. Son principal objectif \u00e9tait de partager les responsabilit\u00e9s relatives \u00e0 la crise migratoire. L\u2019un des domaines dans lequel la Commission Europ\u00e9enne s\u2019est engag\u00e9e \u00e0 agir est justement l\u2019\u00e9ducation puisqu\u2019il s\u2019agit d\u2019un domaine particuli\u00e8rement compliqu\u00e9 \u00e0 g\u00e9rer pour la Turquie. En effet, la Commission Europ\u00e9enne a estim\u00e9 en Mars 2017, que le nombre d\u2019enfants r\u00e9fugi\u00e9s syriens en Turquie atteignait 1,3 millions.<a href=\"#_ftn8\" name=\"_ftnref8\">[8]<\/a> Selon les derniers statistiques obtenus 49% de ces enfants n\u2019\u00e9taient pas enregistr\u00e9s dans une \u00e9cole et, en ce qui concerne les 51% l\u2019\u00e9taient, 18% fr\u00e9quentaient les \u00e9tablissements publics turcs&nbsp; et 32,4% fr\u00e9quentaient les centres de r\u00e9int\u00e9gration \u00e9ducative.<\/p>\n<p>Ces centres ont cependant \u00e9t\u00e9 ferm\u00e9s par l\u2019Etat turc qui craignait que ces centres, dont le curriculum \u00e9tait en arabe, ne permettent pas l\u2019int\u00e9gration des enfants syriens dans le syst\u00e8me turc. Le but de la fermeture de ces centres \u00e9tait donc d\u2019encourager ces enfants \u00e0 int\u00e9grer les \u00e9coles turques. Malheureusement, le r\u00e9sultat obtenu n\u2019a pas \u00e9t\u00e9 celui attendu. En effet, les enfants qui auparavant fr\u00e9quentaient les centres de r\u00e9int\u00e9gration \u00e9ducative n\u2019\u00e9taient pas pr\u00eats \u00e0 int\u00e9grer le syst\u00e8me turc, ce qui a eu pour cons\u00e9quence l\u2019arr\u00eat des \u00e9tudes pour ces enfants. Il s\u2019agit l\u00e0 d\u2019un vide auquel Soutien Belge OverSeas a pour but de trouver des solutions.<\/p>\n<h3>La l\u00e9gislation en vigueur<\/h3>\n<p>La Turquie s\u2019est engag\u00e9e \u00e0 respecter le droit \u00e0 l\u2019\u00e9ducation en ratifiant les principaux trait\u00e9s auxquels elle est partie. Cela inclus la D\u00e9claration Universelle des Droits de l\u2019Homme<a href=\"#_ftn9\" name=\"_ftnref9\">[9]<\/a>, le Pacte International Relatifs aux Droits Economiques, Sociaux et Culturels,<a href=\"#_ftn10\" name=\"_ftnref10\">[10]<\/a> la Convention Internationale des Droits de l\u2019Enfant,<a href=\"#_ftn11\" name=\"_ftnref11\">[11]<\/a> la Convention sur l\u2019Elimination de Toute forme de Discrimination \u00e0 l\u2019\u00e9gard des Femmes<a href=\"#_ftn12\" name=\"_ftnref12\">[12]<\/a> et le Protocole Additionnel \u00e0 la Convention de Sauvegarde des Droits de l\u2019Homme et des Libert\u00e9s Fondamentales.<a href=\"#_ftn13\" name=\"_ftnref13\">[13]<\/a><\/p>\n<p>La Convention Internationale des Droits de l\u2019Enfant en particulier, pr\u00e9voit que les Etats signataires doivent prendre \u00ab&nbsp;<em>les mesures appropri\u00e9es pour qu&#8217;un enfant qui cherche \u00e0 obtenir le statut de r\u00e9fugi\u00e9 ou qui est consid\u00e9r\u00e9 comme r\u00e9fugi\u00e9 en vertu des r\u00e8gles et proc\u00e9dures du droit international ou national applicable, qu&#8217;il soit seul ou accompagn\u00e9 de ses p\u00e8re et m\u00e8re ou de toute autre personne, b\u00e9n\u00e9ficie de la protection et de l&#8217;assistance humanitaire voulues pour lui permettre de jouir des droits que lui reconnaissent la pr\u00e9sente Convention et les autres instruments internationaux relatifs aux droits de l&#8217;homme ou de caract\u00e8re humanitaire auxquels lesdits Etats sont parties<\/em>&nbsp;\u00bb (Article 22).<\/p>\n<p>D\u2019autre part, la Convention relative au Statut de R\u00e9fugi\u00e9 de 1951 et Son protocole additionnel de 1967 disposent que \u00ab&nbsp;<em>les Etats Contractants accorderont aux r\u00e9fugi\u00e9s le m\u00eame traitement qu\u2019aux nationaux en ce qui concerne l\u2019enseignement primaire<\/em>&nbsp;\u00bb et, en ce qui concerne les cat\u00e9gories d\u2019enseignement autre que l\u2019enseignement primaire, qu\u2019ils \u00ab&nbsp;<em>accorderont aux r\u00e9fugi\u00e9s un traitement aussi favorable que possible, et en tout cas non moins favorable que celui qui est accord\u00e9 aux \u00e9trangers en g\u00e9n\u00e9ral dans les m\u00eames circonstances<\/em>&nbsp;\u00bb.<a href=\"#_ftn14\" name=\"_ftnref14\">[14]<\/a> Cependant, parce que la Turquie a \u00e9mis des r\u00e9servations relatives \u00e0 ce trait\u00e9 qui limite son application \u00ab&nbsp;<em>aux personnes qui sont devenues des r\u00e9fugi\u00e9s par suite d&#8217;\u00e9v\u00e9nements survenus en Europe<\/em>&nbsp;\u00bb, excluant donc de son champ d\u2019action les victimes du conflit syrien qui d\u00e9pendent alors de la loi turque sur les&nbsp;\u00e9trangers et la protection internationale de 2013.<\/p>\n<p>Cette loi \u00e9tablit les droits des b\u00e9n\u00e9ficiaires de la Protection Temporaire. En effet, le R\u00e8glement relatif \u00e0 la Protection Temporaire d\u2019octobre 2014 pr\u00e9voit que les b\u00e9n\u00e9ficiaires \u00ab&nbsp;<em>peuvent b\u00e9n\u00e9ficier de [\u2026] l\u2019instruction&nbsp;<\/em>\u00bb et que les cours pour les \u00e9trangers \u00ab&nbsp;<em>devront \u00eatre dispens\u00e9s \u00e0 l\u2019int\u00e9rieur et \u00e0 l\u2019ext\u00e9rieur [des camps] sous le contr\u00f4le et la responsabilit\u00e9 du Minist\u00e8re de l\u2019Education Nationale [\u2026] et en accord avec la l\u00e9gislation du Minist\u00e8re de l\u2019Education Nationale<\/em>&nbsp;\u00bb.<a href=\"#_ftn15\" name=\"_ftnref15\">[15]<\/a><\/p>\n<p>Cependant, au regard des chiffres dont il est fait \u00e9tat dans l\u2019introduction, on peut observer que la situation en Turquie ne r\u00e9pond pas aux normes internationales et nationales en mati\u00e8re de droits de l\u2019homme.<\/p>\n<p>On comprend alors facilement pourquoi la Commission Europ\u00e9enne a mis en place des programmes tels que le Plan d\u2019aide sociale d\u2019urgence et le Transfert d\u2019esp\u00e8ces conditionnel en faveur de l\u2019\u00e9ducation afin de rem\u00e9dier aux difficult\u00e9s d\u2019acc\u00e8s \u00e0 l\u2019\u00e9ducation pour&nbsp;les r\u00e9fugi\u00e9s et demandeurs d\u2019asiles en Turquie. Malheureusement, ces deux m\u00e9canismes ne remplissent pas pleinement leurs objectifs et n\u2019offrent pas de solutions \u00e0 long terme.<\/p>\n<h3>Kilis et Gaziantep d\u00e9laiss\u00e9s<\/h3>\n<p>Compte tenu de tout ceci, Soutien Belge&nbsp;OverSeas&nbsp;a d\u00e9cid\u00e9 de r\u00e9affirmer son engagement envers les r\u00e9fugi\u00e9s et demandeurs d\u2019asile syriens&nbsp;en Turquie.&nbsp;En effet, \u00e0 l\u2019heure actuelle&nbsp;beaucoup d\u2019enfants vivent&nbsp;dans la&nbsp;rue, sont oblig\u00e9 de travailler pour soutenir leurs familles ou ne peuvent simplement pas aller \u00e0 l\u2019\u00e9cole parce qu\u2019ils ne peuvent pas payer pour les transports, les livres et le&nbsp;mat\u00e9riel&nbsp;scolaire. Nous&nbsp;consid\u00e9rons&nbsp;donc essentiel la prise&nbsp;de conscience sur la r\u00e9alit\u00e9 de ces enfants&nbsp;n\u2019ayant pas acc\u00e8s \u00e0 l\u2019\u00e9ducation&nbsp;et sur le besoin urgent de faciliter cet acc\u00e8s. Il s\u2019agit de la seule solution viable pour&nbsp;permettre \u00e0 ces enfants de sortir de&nbsp;la rue&nbsp;et&nbsp;retourner \u00e0 l\u2019\u00e9cole, unique fa\u00e7on pour eux de pouvoir se construire un nouvel avenir.<\/p>\n<p>Malgr\u00e9&nbsp;la pr\u00e9sence de&nbsp;SB&nbsp;OverSeas&nbsp;sur le terrain depuis 2015 gr\u00e2ce \u00e0 nos partenaires&nbsp;\u00e0&nbsp;Kilis&nbsp;et Gaziantep, nous avons rencontr\u00e9s plusieurs difficult\u00e9s pour rassembler&nbsp;des&nbsp;donn\u00e9es&nbsp;exactes&nbsp;sur la situation&nbsp;r\u00e9elle. Cela est principalement d\u00fb \u00e0 l\u2019instabilit\u00e9 de la r\u00e9alit\u00e9 sur le terrain et aux difficult\u00e9s notoires pour obtenir des donn\u00e9es concernant la situation en Turquie. Cependant, gr\u00e2ce \u00e0 ce que nos partenaires ont pu observer sur le terrain, nous pouvons affirmer que le nombre d\u2019enfants&nbsp;non scolaris\u00e9s \u00e0&nbsp;Kilis&nbsp;s\u2019\u00e9l\u00e8ve \u00e0 5.000 sur un total de 150.000 r\u00e9fugi\u00e9s. En&nbsp;ce qui concerne le cas de&nbsp;Gazientep, des statistiques claires ne peuvent pas \u00eatre fournies, mais nous avons pu noter qu\u2019\u00e0 cause de la densit\u00e9 \u00e9lev\u00e9e de la population et du fort taux de ch\u00f4mage, le&nbsp;nombre de r\u00e9fugi\u00e9s dans la rue&nbsp;est&nbsp;consid\u00e9rable.<\/p>\n<p>La raison principale de la pr\u00e9sence&nbsp;d\u2019enfants dans la rue doit \u00eatre attribu\u00e9e \u00e0&nbsp;l\u2019absence de revenus des familles. La pauvret\u00e9 au sein de la communaut\u00e9 des r\u00e9fugi\u00e9s a maintes cons\u00e9quences sur leurs opportunit\u00e9s d\u2019\u00e9ducation. Outre les obstacles rencontr\u00e9s concernant le paiement des transports, des livres et du mat\u00e9riel scolastique, les enfants sont souvent la seule source de revenus au sein de leurs familles.<\/p>\n<p>Une deuxi\u00e8me cause est li\u00e9e aux difficult\u00e9s rencontr\u00e9es pour obtenir la carte d\u2019identit\u00e9 de protection&nbsp;temporaire&nbsp;n\u00e9cessaires aux enfants r\u00e9fugi\u00e9s afin d\u2019int\u00e9grer les \u00e9coles publiques. A&nbsp;Kilis&nbsp;et&nbsp;Gazientep, leur distribution est actuellement suspendue, ce qui emp\u00eache les enfants&nbsp;d\u2019aller \u00e0 l\u2019\u00e9cole. Bloqu\u00e9s&nbsp;dans par cette immobilit\u00e9 administrative, certains&nbsp;enfants ont r\u00e9ussi \u00e0 obtenir&nbsp;la carte d\u2019identit\u00e9 de&nbsp;protection&nbsp;temporaire dans d\u2019autres villes,&nbsp;ce qui les oblige \u00e0 s\u2019inscrire dans&nbsp;l\u2019\u00e9cole dans la ville de d\u00e9livrance de la carte, alors qu\u2019ils habitent \u00e0 Gaziantep ou&nbsp;Kilis.<\/p>\n<p>Un troisi\u00e8me facteur responsable de la non-scolarisation des enfants&nbsp;est la barri\u00e8re linguistique&nbsp;\u00e0 laquelle ils sont confront\u00e9s. Une fois&nbsp;finalement&nbsp;inscrits et accept\u00e9s dans le syst\u00e8me \u00e9ducatif turc, les enfants sont souvent d\u00e9courag\u00e9s&nbsp;parce qu\u2019ils parlent l\u2019arabe et ne comprennent pas le turc.<\/p>\n<p>Cette situation n\u2019est pas nouvelle. La Commission europ\u00e9enne elle-m\u00eame, parmi d\u2019autres organisations internationales, avait&nbsp;fait cette d\u00e9claration dans le cadre de sa volont\u00e9 de contribuer \u00e0 la r\u00e9solution de la \u00ab\u202fcrise des r\u00e9fugi\u00e9s\u202f\u00bb.<a href=\"#_ftn16\" name=\"_ftnref16\">[16]<\/a> N\u00e9anmoins, nous sommes convaincus que cet enjeu n\u2019a pas \u00e9t\u00e9 trait\u00e9 de mani\u00e8re ad\u00e9quate.<\/p>\n<h3>Recommendations<\/h3>\n<p>La mise en place de projets \u00e9ducatifs au Liban&nbsp;est consid\u00e9r\u00e9e comme une grande r\u00e9ussite&nbsp;pour&nbsp;Soutien Belge&nbsp;OverSeas. Ces projets permettent aux enfants r\u00e9fugi\u00e9s d\u2019avoir acc\u00e8s \u00e0 l\u2019\u00e9ducation publique apr\u00e8s avoir particip\u00e9 \u00e0 nos programmes de 6 mois. Sur la base de cette exp\u00e9rience, nous sommes convaincus que des projets similaires sont la meilleure solution pour combler le vide cr\u00e9\u00e9 par les circonstances particuli\u00e8res en Turquie. De plus, les familles de r\u00e9fugi\u00e9s expriment leur d\u00e9sir de pouvoir envoyer leurs enfants \u00e0 l\u2019\u00e9cole et souffrent donc du contexte actuel qui les en emp\u00eachent. D\u00e8s lors, nous demandons \u00e0 la Commission europ\u00e9enne de\u202f:<\/p>\n<ul>\n<li>Publier une \u00e9valuation concernant l\u2019ex\u00e9cution et les&nbsp;r\u00e9sultats des programmes&nbsp;faisant parties de&nbsp;la&nbsp;\u00ab\u202fFacilit\u00e9 en faveur des r\u00e9fugi\u00e9s en Turquie\u202f\u00bb. En effet,&nbsp;ces programmes, y compris le&nbsp;\u00ab\u202fTransfert d\u2019esp\u00e8ces conditionnel en faveur de l\u2019\u00e9ducation\u202f\u00bb&nbsp;(CCTE) mis en place par la Commission europ\u00e9enne en mars 2017, ne sont&nbsp;pas&nbsp;connus par les r\u00e9fugi\u00e9s \u00e0&nbsp;Kilis&nbsp;et Gaziantep. Il y a donc un fort besoin de fournir des informations claires concernant les&nbsp;programmes dans ces r\u00e9gions et d\u2019assurer leur mise en \u0153uvre \u00e0&nbsp;Kilis&nbsp;et&nbsp;Gazientep, malgr\u00e9 les circonstances difficiles.<\/li>\n<li>Augmenter le soutien financier aux ONG qui ont pour mission de venir en aide aux enfants r\u00e9fugi\u00e9s en Turquie. Puisque les ONG locales et internationales jouent un&nbsp;r\u00f4le fondamental&nbsp;dans l\u2019\u00e9ducation des r\u00e9fugi\u00e9s en couvrant les co\u00fbts des transports et du mat\u00e9riel scolaire, il est essentiel de faciliter leurs activit\u00e9s en Turquie o\u00f9 les organisations rencontrent une forte r\u00e9sistance de la part du gouvernement turc. La fermeture d\u2019\u00e9coles de rattrapage et les obstacles que les ONG rencontrent dans le domaine de l\u2019\u00e9ducation en sont des exemples.<\/li>\n<li>De s\u2019assurer que les fonds vers\u00e9s \u00e0 la Turquie par la Commission europ\u00e9enne,&nbsp;destin\u00e9s aux ONG, soient dans la pratique utilis\u00e9s par ces derni\u00e8res.<\/li>\n<\/ul>\n<p>Le besoin de favoriser l\u2019acc\u00e8s \u00e0 l\u2019\u00e9ducation des enfants en Turquie gr\u00e2ce \u00e0 des programmes temporaires est notamment d\u00e9montr\u00e9 par la cr\u00e9ation de quelques \u00e9coles de ce type par des familles (comme c\u2019est le cas \u00e0&nbsp;Kilis) ou par des ONG qui essayent de donner une formation aux r\u00e9fugi\u00e9s mais qui ne disposent&nbsp;pas de moyens appropri\u00e9s et de ressources suffisantes. Il s\u2019agit l\u00e0 d\u2019un signe d\u2019espoir, mais l\u2019action de la communaut\u00e9&nbsp;internationale est indispensable pour am\u00e9liorer la qualit\u00e9 de l\u2019\u00e9ducation et augmenter le nombre d\u2019enfants inscrits dans les \u00e9coles.<\/p>\n<hr>\n<p class=\"sd-margin-none\"><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> UNHCR, Global Trends, <a href=\"http:\/\/www.unhcr.org\/5943e8a34.pdf\"><em>Forced Displacement in 2016<\/em><\/a>, p.2<\/p>\n<p class=\"sd-margin-none\"><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Ibid. p.6<\/p>\n<p class=\"sd-margin-none\"><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> Portail Interagence de partage de l&#8217;Information, <a href=\"http:\/\/data.unhcr.org\/syrianrefugees\/regional.php\">R\u00e9ponse R\u00e9gionale \u00e0&nbsp; la crise des R\u00e9fugi\u00e9s en Syrie<\/a><\/p>\n<p class=\"sd-margin-none\"><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> Portail Interagence de partage de l&#8217;Information, R\u00e9ponse R\u00e9gionale \u00e0&nbsp; la crise des R\u00e9fugi\u00e9s en Syrie, <a href=\"http:\/\/data.unhcr.org\/syrianrefugees\/country.php?id=224\">Turquie<\/a><\/p>\n<p class=\"sd-margin-none\"><a href=\"#_ftnref5\" name=\"_ftn5\">[5]<\/a> Ibid. note 1, p.3<\/p>\n<p class=\"sd-margin-none\"><a href=\"#_ftnref6\" name=\"_ftn6\">[6]<\/a> Ba\u015fak Yav\u00e7an, PhD TOBB University of Economics and Technology, FNF &amp; Ralf Dahrendorf Roundtables, <em>Fostering Successful Integration of Syrian Refugees in Turkey<\/em>, Sept 26th, 2017 Brussels.<\/p>\n<p class=\"sd-margin-none\"><a href=\"#_ftnref7\" name=\"_ftn7\">[7]<\/a> Ibid.<\/p>\n<p class=\"sd-margin-none\"><a href=\"#_ftnref8\" name=\"_ftn8\">[8]<\/a> EU and UNICEF joint Press Release, <em>EU and UNICEF to reach thousands of refugee children in Turkey with Conditional Cash Transfer for Education<\/em>, 16 March 2017<\/p>\n<p class=\"sd-margin-none\"><a href=\"#_ftnref9\" name=\"_ftn9\">[9]<\/a> Cf. article 26, adopt\u00e9e le 10 d\u00e9cembre 1948<\/p>\n<p class=\"sd-margin-none\"><a href=\"#_ftnref10\" name=\"_ftn10\">[10]<\/a> Cf. Article 13, ratifi\u00e9 par la Turquie en 2003<\/p>\n<p class=\"sd-margin-none\"><a href=\"#_ftnref11\" name=\"_ftn11\">[11]<\/a> Cf. Article 28, ratifi\u00e9 par la Turquie en 1995<\/p>\n<p class=\"sd-margin-none\"><a href=\"#_ftnref12\" name=\"_ftn12\">[12]<\/a> Cf. Article 10, ratifi\u00e9 par la Turquie en 1985<\/p>\n<p class=\"sd-margin-none\"><a href=\"#_ftnref13\" name=\"_ftn13\">[13]<\/a> Cf. Article 2, ratifi\u00e9 par la Turquie en 1954<\/p>\n<p class=\"sd-margin-none\"><a href=\"#_ftnref14\" name=\"_ftn14\">[14]<\/a> Cf. Article 22, ratifi\u00e9 par la Turquie en 1968<\/p>\n<p class=\"sd-margin-none\"><a href=\"#_ftnref15\" name=\"_ftn15\">[15]<\/a> Cf. Article 22<\/p>\n<p class=\"sd-margin-none\"><a href=\"#_ftnref16\" name=\"_ftn16\">[16]<\/a> Commission Europ\u00e9enne, <a href=\"https:\/\/www.dropbox.com\/referrer_cleansing_redirect?hmac=ziBzzqM8r%2B%2FQ990ZM4vFGozd%2BwNOvpnUQp5ia9SEm6c%3D&amp;url=http%3A%2F%2Fec.europa.eu%2Fecho%2Ffiles%2Faid%2Fcountries%2Ffactsheets%2Fturkey_syrian_crisis_en.pdf\">European Civil Protection and Humanitarian Aid Operations<\/a>, 16 Octobre 2017<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Selon le dernier rapport du HCR, \u00ab&nbsp;Global Trends, Forced Displacement&nbsp;\u00bb, fin 2016, 65,5 millions de personnes avaient \u00e9t\u00e9 d\u00e9plac\u00e9es \u00e0 cause des pers\u00e9cutions subies, des conflits, des violences ou des violations des Droits de l\u2019Homme.[1] Parmis ces 65,5 millions de personnes d\u00e9plac\u00e9es, 22,5 sont enregistr\u00e9es comme r\u00e9fugi\u00e9s.[2] Aujourd\u2019hui, Portail Interagence de partage de l&#8217;Information indique [&hellip;]<\/p>","protected":false},"author":162,"featured_media":2627,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[88,129],"tags":[],"class_list":["post-2628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communiques-de-presse","category-education-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019Education en Turquie inaccessible \u00e0 des milliers d\u2019enfants r\u00e9fugi\u00e9s Syriens - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sboverseas.org\/nl\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Education en Turquie inaccessible \u00e0 des milliers d\u2019enfants r\u00e9fugi\u00e9s Syriens - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"og:description\" content=\"Selon le dernier rapport du HCR, \u00ab&nbsp;Global Trends, Forced Displacement&nbsp;\u00bb, fin 2016, 65,5 millions de personnes avaient \u00e9t\u00e9 d\u00e9plac\u00e9es \u00e0 cause des pers\u00e9cutions subies, des conflits, des violences ou des violations des Droits de l\u2019Homme.[1] Parmis ces 65,5 millions de personnes d\u00e9plac\u00e9es, 22,5 sont enregistr\u00e9es comme r\u00e9fugi\u00e9s.[2] Aujourd\u2019hui, Portail Interagence de partage de l&#8217;Information indique [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sboverseas.org\/nl\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/\" \/>\n<meta property=\"og:site_name\" content=\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-17T16:05:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sboverseas.org\/wp-content\/uploads\/2017\/11\/Article-Turkey-e1513774317129.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sboverseas.org\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/\",\"url\":\"https:\/\/sboverseas.org\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/\",\"name\":\"L\u2019Education en Turquie inaccessible \u00e0 des milliers d\u2019enfants r\u00e9fugi\u00e9s Syriens - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"isPartOf\":{\"@id\":\"https:\/\/sboverseas.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sboverseas.org\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sboverseas.org\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2017\/11\/Article-Turkey-e1513774317129.jpg\",\"datePublished\":\"2017-11-17T16:05:19+00:00\",\"author\":{\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sboverseas.org\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/sboverseas.org\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/#primaryimage\",\"url\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2017\/11\/Article-Turkey-e1513774317129.jpg\",\"contentUrl\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2017\/11\/Article-Turkey-e1513774317129.jpg\",\"width\":720,\"height\":540},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sboverseas.org\/#website\",\"url\":\"https:\/\/sboverseas.org\/\",\"name\":\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"description\":\"Give Hope\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sboverseas.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sboverseas.org\"],\"url\":\"https:\/\/sboverseas.org\/nl\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019Education en Turquie inaccessible \u00e0 des milliers d\u2019enfants r\u00e9fugi\u00e9s Syriens - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sboverseas.org\/nl\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/","og_locale":"nl_NL","og_type":"article","og_title":"L\u2019Education en Turquie inaccessible \u00e0 des milliers d\u2019enfants r\u00e9fugi\u00e9s Syriens - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","og_description":"Selon le dernier rapport du HCR, \u00ab&nbsp;Global Trends, Forced Displacement&nbsp;\u00bb, fin 2016, 65,5 millions de personnes avaient \u00e9t\u00e9 d\u00e9plac\u00e9es \u00e0 cause des pers\u00e9cutions subies, des conflits, des violences ou des violations des Droits de l\u2019Homme.[1] Parmis ces 65,5 millions de personnes d\u00e9plac\u00e9es, 22,5 sont enregistr\u00e9es comme r\u00e9fugi\u00e9s.[2] Aujourd\u2019hui, Portail Interagence de partage de l&#8217;Information indique [&hellip;]","og_url":"https:\/\/sboverseas.org\/nl\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/","og_site_name":"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","article_published_time":"2017-11-17T16:05:19+00:00","og_image":[{"width":720,"height":540,"url":"https:\/\/sboverseas.org\/wp-content\/uploads\/2017\/11\/Article-Turkey-e1513774317129.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"admin","Geschatte leestijd":"12 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sboverseas.org\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/","url":"https:\/\/sboverseas.org\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/","name":"L\u2019Education en Turquie inaccessible \u00e0 des milliers d\u2019enfants r\u00e9fugi\u00e9s Syriens - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","isPartOf":{"@id":"https:\/\/sboverseas.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sboverseas.org\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/#primaryimage"},"image":{"@id":"https:\/\/sboverseas.org\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/#primaryimage"},"thumbnailUrl":"https:\/\/sboverseas.org\/wp-content\/uploads\/2017\/11\/Article-Turkey-e1513774317129.jpg","datePublished":"2017-11-17T16:05:19+00:00","author":{"@id":"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sboverseas.org\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/sboverseas.org\/leducation-en-turquie-inaccessible-a-des-milliers-denfants-refugies-syriens\/#primaryimage","url":"https:\/\/sboverseas.org\/wp-content\/uploads\/2017\/11\/Article-Turkey-e1513774317129.jpg","contentUrl":"https:\/\/sboverseas.org\/wp-content\/uploads\/2017\/11\/Article-Turkey-e1513774317129.jpg","width":720,"height":540},{"@type":"WebSite","@id":"https:\/\/sboverseas.org\/#website","url":"https:\/\/sboverseas.org\/","name":"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","description":"Give Hope","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sboverseas.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d","name":"admin","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/sboverseas.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/sboverseas.org"],"url":"https:\/\/sboverseas.org\/nl\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sboverseas.org\/nl\/wp-json\/wp\/v2\/posts\/2628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sboverseas.org\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sboverseas.org\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/nl\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/nl\/wp-json\/wp\/v2\/comments?post=2628"}],"version-history":[{"count":0,"href":"https:\/\/sboverseas.org\/nl\/wp-json\/wp\/v2\/posts\/2628\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/nl\/wp-json\/wp\/v2\/media\/2627"}],"wp:attachment":[{"href":"https:\/\/sboverseas.org\/nl\/wp-json\/wp\/v2\/media?parent=2628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sboverseas.org\/nl\/wp-json\/wp\/v2\/categories?post=2628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sboverseas.org\/nl\/wp-json\/wp\/v2\/tags?post=2628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}