{"id":6584,"date":"2019-04-10T14:57:21","date_gmt":"2019-04-10T12:57:21","guid":{"rendered":"https:\/\/sboverseas.org\/?p=6584"},"modified":"2019-04-10T14:57:21","modified_gmt":"2019-04-10T12:57:21","slug":"welcome-to-shatila","status":"publish","type":"post","link":"https:\/\/sboverseas.org\/fr\/welcome-to-shatila\/","title":{"rendered":"Bienvenue \u00e0 Chatila"},"content":{"rendered":"<p>A l&#039;ombre d&#039;\u00e9pais nuages noirs venant des montagnes, un soir de f\u00e9vrier \u00e0 Beyrouth, je montai \u00e0 l&#039;arri\u00e8re d&#039;un taxi \u00e0 Gemmayze ; le quartier historique et boh\u00e8me de la ville, peupl\u00e9 de hipsters et d&#039;artistes, et je me suis pr\u00e9par\u00e9 mentalement \u00e0 l&#039;endroit o\u00f9 j&#039;allais aller. Je pensais que les images que j&#039;avais vues dans les articles et dans mon esprit me pr\u00e9pareraient dans une certaine mesure \u00e0 ce que j&#039;allais ressentir, je n&#039;aurais pas pu me tromper davantage.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/theworldwidetribe.com\/wp-content\/uploads\/2019\/03\/IMG_5825-e1553727234981.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/theworldwidetribe.com\/wp-content\/uploads\/2019\/03\/IMG_5334.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Je m&#039;appelle Katherine et je travaille avec Jaz \u00e0&nbsp;<a href=\"https:\/\/theworldwidetribe.com\/\">La tribu mondiale<\/a>. Je suis venu \u00e0 Beyrouth pour trois mois pour faire du b\u00e9n\u00e9volat avec&nbsp;<a href=\"https:\/\/sboverseas.org\/fr\/home\/\">SB Overseas<\/a>, une jeune ONG bruxelloise avec qui nous sommes en contact depuis un certain temps. Les op\u00e9rations sur le terrain de SB sont stationn\u00e9es au Liban, o\u00f9 leur petite \u00e9quipe d&#039;enseignants, d&#039;administrateurs et de psychologues syriens consacrent leur vie \u00e0 \u00e9duquer et \u00e0 soutenir les femmes et les enfants r\u00e9fugi\u00e9s syriens dans leurs trois \u00e9coles situ\u00e9es \u00e0 Arsal, Saida, et ici au centre de Beyrouth, Bukra Ahla \u2013 \u00ab un avenir meilleur \u00bb, o\u00f9 la majorit\u00e9 des \u00e9tudiants viennent du camp de r\u00e9fugi\u00e9s voisin de Chatila. \u00c0 l&#039;origine un camp palestinien, cr\u00e9\u00e9 en 1949 pour accueillir l&#039;afflux de r\u00e9fugi\u00e9s fuyant la guerre isra\u00e9lo-arabe, Chatila abrite aujourd&#039;hui des milliers de r\u00e9fugi\u00e9s syriens.<\/p>\n\n\n\n<p>Trouver un taxi pr\u00eat \u00e0 m&#039;amener ici \u00e9tait un d\u00e9fi en soi. Beaucoup ont cat\u00e9goriquement refus\u00e9, d&#039;autres m&#039;ont donn\u00e9 de longues conf\u00e9rences en arabe m&#039;avertissant de rester \u00e0 l&#039;\u00e9cart. Une fois que j&#039;ai trouv\u00e9 un chauffeur coop\u00e9ratif, nous sommes finalement pass\u00e9s par le point de contr\u00f4le surveillant tous ceux qui souhaitaient entrer ou sortir, et j&#039;ai commenc\u00e9 \u00e0 comprendre.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/theworldwidetribe.com\/wp-content\/uploads\/2019\/03\/IMG_0144.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Mon sentiment honn\u00eate entrant dans cet endroit? Inconfortable, tr\u00e8s inconfortable. Venant de la belle Gemmayze, le contraste est saisissant. Je suis sorti du taxi dans une rue poussi\u00e9reuse et sale avec le crissement oppressant du sciage r\u00e9sonnant dans mes oreilles et d&#039;\u00e9paisses vapeurs de diesel remplissant mes poumons. Wael, le directeur du centre m&#039;a accueilli avec un sourire chaleureux et a \u00e9paul\u00e9 mon sac. Ensemble, nous sommes entr\u00e9s dans un vieux gratte-ciel et il m&#039;a montr\u00e9 l&#039;appartement que je partagerais avec sept autres personnes pendant mon s\u00e9jour ici, quelques \u00e9tages au-dessus de l&#039;\u00e9cole. Je me suis couch\u00e9 t\u00f4t et je suis rest\u00e9 \u00e9veill\u00e9, les yeux ouverts dans le noir pendant un long moment, me sentant coupable de mon inconfort, jusqu&#039;\u00e0 ce que je finisse par sombrer dans un sommeil agit\u00e9.<\/p>\n\n\n\n<p>Le lendemain matin, je suis entr\u00e9 dans Bukra Ahla. Le n\u0153ud dans mon estomac a imm\u00e9diatement commenc\u00e9 \u00e0 se d\u00e9faire \u00e0 la vue des murs lumineux et color\u00e9s, des sourires accueillants et du ch\u0153ur joyeux d&#039;ABC r\u00e9sonnant dans le centre. Mon seul travail de la journ\u00e9e \u00e9tait d&#039;observer les cours. Je n&#039;ai jamais v\u00e9cu un revirement \u00e9motionnel aussi dramatique. Observant les professeurs syriens magn\u00e9tiques, Ahmed, Ahmed, Safa et Abdhulla, et les volontaires enseignant \u00e0 leurs \u00e9tudiants dynamiques et amusants l&#039;anglais, l&#039;arabe, les math\u00e9matiques, les sciences et les comp\u00e9tences de vie, mon c\u0153ur a \u00e9clat\u00e9. En moins d&#039;une heure, j&#039;\u00e9tais tomb\u00e9 compl\u00e8tement amoureux de l&#039;\u00e9cole et de tous ceux qui s&#039;y trouvaient. \u00c0 partir de ce moment, je me suis sentie si privil\u00e9gi\u00e9e d&#039;avoir \u00e9t\u00e9 accueillie dans cette famille.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/theworldwidetribe.com\/wp-content\/uploads\/2019\/03\/The-Worldwide-Tribe-Katherine-e1553727108193.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/theworldwidetribe.com\/wp-content\/uploads\/2019\/03\/IMG_9401-1-1.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>La semaine derni\u00e8re, nous avons travers\u00e9 la rue et sommes entr\u00e9s pour la premi\u00e8re fois dans le camp de r\u00e9fugi\u00e9s de Chatila, dans lequel nous ne pouvons entrer correctement sans surveillance. Aucune photo ou article n&#039;aurait pu me pr\u00e9parer. Ce labyrinthe de ruelles \u00e9troites est claustrophobe, sale, surpeupl\u00e9 et humide. Au-dessus de nos t\u00eates, un \u00e9pais enchev\u00eatrement de tuyaux et de fils \u00e9lectriques sous tension expos\u00e9s forme une toile dangereuse et d\u00e9goulinante sur le camp. Je pense aux enfants plus \u00e2g\u00e9s, qui ont encore des souvenirs de leurs maisons autrefois chaleureuses et heureuses en Syrie, quittant l&#039;\u00e9cole et rentrant chez eux tous les jours. Je pense aux plus jeunes enfants, encore des b\u00e9b\u00e9s, n\u00e9s dans ce camp, \u00e0 la fa\u00e7on dont ils courent dans nos salles de classe s\u00fbres et propres, grimpant sur des chaises et touchant tout avec leurs petites mains parfaites, avec une curiosit\u00e9 si innocente et enthousiaste, et je me sens malade comme J&#039;imagine ces petites mains faisant la m\u00eame chose ici. J&#039;ai profond\u00e9ment honte de mon propre malaise quand je suis arriv\u00e9. Je n&#039;ai pas entendu un seul Syrien se plaindre de ses conditions de vie. Les mots \u00ab\u00a0mal \u00e0 l&#039;aise\u00a0\u00bb et \u00ab\u00a0r\u00e9silience\u00a0\u00bb ont ici des d\u00e9finitions diff\u00e9rentes.<\/p>\n\n\n\n<p>SB Overseas est sans aucun doute une lumi\u00e8re brillante dans cet endroit sombre. Cette ONG, cette famille, construite par des r\u00e9fugi\u00e9s pour des r\u00e9fugi\u00e9s, se bat pour donner \u00e0 ces enfants innocents et incroyables un endroit s\u00fbr et heureux pour qu&#039;ils apprennent, jouent et soient des enfants, comme les enfants sont cens\u00e9s l&#039;\u00eatre. Il se bat pour leur donner les opportunit\u00e9s, les espoirs et les r\u00eaves qu&#039;ils m\u00e9ritent tant. Il se bat contre la perte de cette g\u00e9n\u00e9ration de beaux enfants dans une guerre qu&#039;ils n&#039;ont jamais demand\u00e9e.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/theworldwidetribe.com\/wp-content\/uploads\/2019\/03\/IMG_0187-4.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/theworldwidetribe.com\/wp-content\/uploads\/2019\/03\/IMG_9446.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>M\u00eame si je veux sentir qu&#039;il n&#039;y a rien qui me s\u00e9pare de ma nouvelle famille SB, ou de ces enfants incroyables, la v\u00e9rit\u00e9 inconfortable et in\u00e9vitable demeure\u2026 alors que je marche dans les rues humides et sales de Chatila, pour mon passeport britannique et Moi, \u00eatre ici est un choix. Pour eux, c&#039;est une phrase, sans fin claire en vue. Je peux partir et rentrer chez moi quand je veux. Ils ne peuvent jamais.<\/p>\n\n\n\n<p>Et soudain, je r\u00e9alise ce qui me met vraiment mal \u00e0 l&#039;aise \u00e0 ce sujet, \u00e0 cause de mon passeport et du pays s\u00fbr et privil\u00e9gi\u00e9 dans lequel je suis n\u00e9, moi et nous tous, pouvons choisir de reconna\u00eetre leur souffrance ou de d\u00e9tourner le regard maladroitement et de pr\u00e9tendre que nous ne peut pas voir. Nous pouvons choisir de nous tenir \u00e0 c\u00f4t\u00e9 d&#039;eux ou de nous en aller. De tout mon c\u0153ur, je choisis de les voir et de me tenir \u00e0 leurs c\u00f4t\u00e9s, et je referai ce choix chaque jour jusqu&#039;\u00e0 ce qu&#039;ils aient la possibilit\u00e9 de vivre comme moi.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Je parlerai davantage de SB Overseas et vous pr\u00e9senterai certains de mes incroyables coll\u00e8gues et \u00e9tudiants dans les semaines \u00e0 venir, SB ne peut pas continuer le travail incroyable qu&#039;il fait sans soutien. Tout ce que vous \u00eates en mesure de donner ferait une \u00e9norme diff\u00e9rence pour ces enfants, et il suffit de lire ces messages et de vous engager \u00e0 les voir et \u00e0 les soutenir. Merci pour votre soutien.&nbsp;<\/p>\n\n\n\n<p>Donner espoir.<\/p>\n\n\n\n<p><a href=\"https:\/\/mydonate.bt.com\/events\/lebanon\/490606\">FAITES UN DON<\/a><\/p>\n\n\n\n<p><em>\u00c9crit par la volontaire libanaise Katherine Hajiyianni. <\/em><br><em>Publi\u00e9 pour la premi\u00e8re fois le\u00a0<a href=\"https:\/\/theworldwidetribe.com\/sb-overseas\/\">La tribu mondiale<\/a><\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Under the shadow of thick, black clouds sweeping in from the mountains one February evening in Beirut I climbed into the back of a taxi in Gemmayze; the historic, bohemian quarter of the city, populated by hipsters and artists, and mentally braced myself for where I was about to go. I thought the pictures I [&hellip;]<\/p>","protected":false},"author":162,"featured_media":6585,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[65,110,63],"tags":[235,61],"class_list":["post-6584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emergency-aid-en","category-lebanon","category-volunteer-blogs","tag-day-in-the-life","tag-shatila"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Welcome to Shatila - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sboverseas.org\/fr\/welcome-to-shatila\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Welcome to Shatila - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"og:description\" content=\"Under the shadow of thick, black clouds sweeping in from the mountains one February evening in Beirut I climbed into the back of a taxi in Gemmayze; the historic, bohemian quarter of the city, populated by hipsters and artists, and mentally braced myself for where I was about to go. I thought the pictures I [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sboverseas.org\/fr\/welcome-to-shatila\/\" \/>\n<meta property=\"og:site_name\" content=\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-10T12:57:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sboverseas.org\/wp-content\/uploads\/2019\/04\/IMG_5827.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sboverseas.org\/nl\/welcome-to-shatila\/\",\"url\":\"https:\/\/sboverseas.org\/nl\/welcome-to-shatila\/\",\"name\":\"Welcome to Shatila - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"isPartOf\":{\"@id\":\"https:\/\/sboverseas.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sboverseas.org\/nl\/welcome-to-shatila\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sboverseas.org\/nl\/welcome-to-shatila\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2019\/04\/IMG_5827.jpg\",\"datePublished\":\"2019-04-10T12:57:21+00:00\",\"author\":{\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sboverseas.org\/nl\/welcome-to-shatila\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/sboverseas.org\/nl\/welcome-to-shatila\/#primaryimage\",\"url\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2019\/04\/IMG_5827.jpg\",\"contentUrl\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2019\/04\/IMG_5827.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sboverseas.org\/#website\",\"url\":\"https:\/\/sboverseas.org\/\",\"name\":\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"description\":\"Give Hope\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sboverseas.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sboverseas.org\"],\"url\":\"https:\/\/sboverseas.org\/fr\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Welcome to Shatila - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sboverseas.org\/fr\/welcome-to-shatila\/","og_locale":"fr_FR","og_type":"article","og_title":"Welcome to Shatila - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","og_description":"Under the shadow of thick, black clouds sweeping in from the mountains one February evening in Beirut I climbed into the back of a taxi in Gemmayze; the historic, bohemian quarter of the city, populated by hipsters and artists, and mentally braced myself for where I was about to go. I thought the pictures I [&hellip;]","og_url":"https:\/\/sboverseas.org\/fr\/welcome-to-shatila\/","og_site_name":"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","article_published_time":"2019-04-10T12:57:21+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/sboverseas.org\/wp-content\/uploads\/2019\/04\/IMG_5827.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture est.":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sboverseas.org\/nl\/welcome-to-shatila\/","url":"https:\/\/sboverseas.org\/nl\/welcome-to-shatila\/","name":"Welcome to Shatila - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","isPartOf":{"@id":"https:\/\/sboverseas.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sboverseas.org\/nl\/welcome-to-shatila\/#primaryimage"},"image":{"@id":"https:\/\/sboverseas.org\/nl\/welcome-to-shatila\/#primaryimage"},"thumbnailUrl":"https:\/\/sboverseas.org\/wp-content\/uploads\/2019\/04\/IMG_5827.jpg","datePublished":"2019-04-10T12:57:21+00:00","author":{"@id":"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sboverseas.org\/nl\/welcome-to-shatila\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/sboverseas.org\/nl\/welcome-to-shatila\/#primaryimage","url":"https:\/\/sboverseas.org\/wp-content\/uploads\/2019\/04\/IMG_5827.jpg","contentUrl":"https:\/\/sboverseas.org\/wp-content\/uploads\/2019\/04\/IMG_5827.jpg","width":2048,"height":1365},{"@type":"WebSite","@id":"https:\/\/sboverseas.org\/#website","url":"https:\/\/sboverseas.org\/","name":"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","description":"Give Hope","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sboverseas.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Person","@id":"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/sboverseas.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/sboverseas.org"],"url":"https:\/\/sboverseas.org\/fr\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts\/6584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/comments?post=6584"}],"version-history":[{"count":0,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts\/6584\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/media\/6585"}],"wp:attachment":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/media?parent=6584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/categories?post=6584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/tags?post=6584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}