{"id":5150,"date":"2019-01-17T17:56:25","date_gmt":"2019-01-17T16:56:25","guid":{"rendered":"https:\/\/sboverseas.org\/?p=5150"},"modified":"2019-01-17T17:56:25","modified_gmt":"2019-01-17T16:56:25","slug":"urgent-call-arsal-storm-crisis","status":"publish","type":"post","link":"https:\/\/sboverseas.org\/fr\/urgent-call-arsal-storm-crisis\/","title":{"rendered":"APPEL URGENT\u00a0: crise de la temp\u00eate d&#039;Arsal"},"content":{"rendered":"<h4 class=\"wp-block-heading\">Nous comptons sur vous pour venir en aide aux 70 000 r\u00e9fugi\u00e9s syriens menac\u00e9s par les temp\u00eates de neige, les inondations et le gel au Liban <\/h4>\n\n\n\n<table class=\"wp-block-table is-style-stripes\"><tbody><tr><td><\/td><\/tr><tr><td><strong>Bruxelles, Belgique -<\/strong> Avec en toile de fond les montagnes enneig\u00e9es de l&#039;Anti-Liban et les nuages d&#039;orage blancs et moelleux dans le ciel, les tentes du HCR sont couvertes d&#039;une \u00e9paisse neige blanche : c&#039;est la r\u00e9alit\u00e9 \u00e0 Arsal, l&#039;un des plus grands camps de r\u00e9fugi\u00e9s syriens au Liban, dans l&#039;un des plus r\u00e9gions pr\u00e9caires du pays. <br><br>Depuis l&#039;arriv\u00e9e de la temp\u00eate Norma le 6 janvier, de fortes pluies et des chutes de neige ont frapp\u00e9 le Liban, touchant plus durement la ville frontali\u00e8re d&#039;Arsal. Plus de 22 000 r\u00e9fugi\u00e9s vivant dans le camp sont confront\u00e9s \u00e0 des temp\u00e9ratures glaciales, \u00e0 des vents violents et \u00e0 la menace imminente que les habitations temporaires de 250 000 familles de r\u00e9fugi\u00e9s soient d\u00e9truites par le poids de la neige ou des inondations. <br><br><em><strong>Mais le mauvais temps continue. <\/strong><\/em><br><br>La temp\u00eate Miriam apporte plus de neige, ainsi que de la gr\u00eale, des orages et des vents violents, qui devraient d\u00e9passer les 100 km\/h. Le HCR estime que 70 000 r\u00e9fugi\u00e9s sont menac\u00e9s par cette temp\u00eate. M\u00eame avec les pr\u00e9visions futures pr\u00e9voyant du soleil, la situation peut s&#039;aggraver en raison de la fonte des neiges qui s&#039;infiltre et inonde les abris. <\/td><\/tr><\/tbody><\/table>\n\n\n\n<p>Avec votre aide, nous pouvons fournir \u00e0 chaque famille les mat\u00e9riaux suffisants pour les garder au chaud pendant les semaines d&#039;hiver restantes. Chaque famille a un besoin urgent d&#039;une couverture de protection pour isoler son abri du froid, de couvertures et de plusieurs litres de Mazout (le combustible libanais n\u00e9cessaire pour chauffer son abri).\n<\/p>\n\n\n\n<p style=\"text-align:center\">30 EUR en ach\u00e8te un <strong>couvercle de protection<\/strong> pour isoler l&#039;abri d&#039;une famille<br> 18 EUR paie pour un <strong>couverture<\/strong><br> 20 EUR ach\u00e8tent vingt-deux litres de <strong>Combustible Mazout <\/strong>n\u00e9cessaire pour chauffer un abri 12 EUR ach\u00e8te 1kg de <strong>lait f<\/strong>ou des enfants <\/p>\n\n\n\n<p>Veuillez faire n&#039;importe <strong>dons mon\u00e9taires<\/strong> par virement bancaire ou Paypal avec le terme \u00ab Arsal \u00bb comme r\u00e9f\u00e9rence : compte Paypal : sdk.be@hotmail.com (compte professionnel) <\/p>\n\n\n\n<p style=\"text-align:center\"><strong>compte bancaire <\/strong><br>Banque : Banque CBC BE42 7320 3907 1954 <br>SWIFT\u00a0: CREGBEBB <br>D\u00e9nomination : SB outre-mer asbl <br>Adresse Braine L-alleud <\/p>\n\n\n\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<br> SB Overseas est enregistr\u00e9e en tant qu&#039;association \u00e0 but non lucratif en Belgique (num\u00e9ro d&#039;enregistrement : BE 0533.981.634). Cette collecte de fonds est li\u00e9e au compte bancaire de SB Overseas. Pour ceux aux \u00c9tats-Unis, des dons au SB Overseas US Fund via la page \u00c9tats-Unis de la Fondation Roi Baudouin https:\/\/kbfus.networkforgood.com\/projects\/35528-s-kbfus-funds-sb-overseas-be?  <\/p>","protected":false},"excerpt":{"rendered":"<p>We are counting on you to help the 70,000 Syrian refugees in danger from snow storms, flooding and freezing in Lebanon BRUSSELS, Belgium \u2013 Against the backdrop of the snowcapped Anti-Lebanon mountains and pillowy white storm clouds in the sky, UNHCR tents are covered by dense white snow: this is the reality in Arsal, one [&hellip;]<\/p>","protected":false},"author":162,"featured_media":5154,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[50,110,55,1],"tags":[51,77,59,56],"class_list":["post-5150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-advocacy","category-lebanon","category-press-releases","category-uncategorized","tag-arsal","tag-crisis","tag-lebanon","tag-refugee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>URGENT CALL: Arsal Storm Crisis - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sboverseas.org\/fr\/urgent-call-arsal-storm-crisis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"URGENT CALL: Arsal Storm Crisis - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"og:description\" content=\"We are counting on you to help the 70,000 Syrian refugees in danger from snow storms, flooding and freezing in Lebanon BRUSSELS, Belgium \u2013 Against the backdrop of the snowcapped Anti-Lebanon mountains and pillowy white storm clouds in the sky, UNHCR tents are covered by dense white snow: this is the reality in Arsal, one [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sboverseas.org\/fr\/urgent-call-arsal-storm-crisis\/\" \/>\n<meta property=\"og:site_name\" content=\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-17T16:56:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sboverseas.org\/wp-content\/uploads\/2019\/01\/50411450_2222764207746758_1547410269309763584_o.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1068\" \/>\n\t<meta property=\"og:image:height\" content=\"712\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sboverseas.org\/nl\/urgent-call-arsal-storm-crisis\/\",\"url\":\"https:\/\/sboverseas.org\/nl\/urgent-call-arsal-storm-crisis\/\",\"name\":\"URGENT CALL: Arsal Storm Crisis - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"isPartOf\":{\"@id\":\"https:\/\/sboverseas.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sboverseas.org\/nl\/urgent-call-arsal-storm-crisis\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sboverseas.org\/nl\/urgent-call-arsal-storm-crisis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2019\/01\/50411450_2222764207746758_1547410269309763584_o.jpg\",\"datePublished\":\"2019-01-17T16:56:25+00:00\",\"author\":{\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sboverseas.org\/nl\/urgent-call-arsal-storm-crisis\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/sboverseas.org\/nl\/urgent-call-arsal-storm-crisis\/#primaryimage\",\"url\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2019\/01\/50411450_2222764207746758_1547410269309763584_o.jpg\",\"contentUrl\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2019\/01\/50411450_2222764207746758_1547410269309763584_o.jpg\",\"width\":1068,\"height\":712},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sboverseas.org\/#website\",\"url\":\"https:\/\/sboverseas.org\/\",\"name\":\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"description\":\"Give Hope\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sboverseas.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sboverseas.org\"],\"url\":\"https:\/\/sboverseas.org\/fr\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"URGENT CALL: Arsal Storm Crisis - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sboverseas.org\/fr\/urgent-call-arsal-storm-crisis\/","og_locale":"fr_FR","og_type":"article","og_title":"URGENT CALL: Arsal Storm Crisis - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","og_description":"We are counting on you to help the 70,000 Syrian refugees in danger from snow storms, flooding and freezing in Lebanon BRUSSELS, Belgium \u2013 Against the backdrop of the snowcapped Anti-Lebanon mountains and pillowy white storm clouds in the sky, UNHCR tents are covered by dense white snow: this is the reality in Arsal, one [&hellip;]","og_url":"https:\/\/sboverseas.org\/fr\/urgent-call-arsal-storm-crisis\/","og_site_name":"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","article_published_time":"2019-01-17T16:56:25+00:00","og_image":[{"width":1068,"height":712,"url":"https:\/\/sboverseas.org\/wp-content\/uploads\/2019\/01\/50411450_2222764207746758_1547410269309763584_o.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture est.":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sboverseas.org\/nl\/urgent-call-arsal-storm-crisis\/","url":"https:\/\/sboverseas.org\/nl\/urgent-call-arsal-storm-crisis\/","name":"URGENT CALL: Arsal Storm Crisis - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","isPartOf":{"@id":"https:\/\/sboverseas.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sboverseas.org\/nl\/urgent-call-arsal-storm-crisis\/#primaryimage"},"image":{"@id":"https:\/\/sboverseas.org\/nl\/urgent-call-arsal-storm-crisis\/#primaryimage"},"thumbnailUrl":"https:\/\/sboverseas.org\/wp-content\/uploads\/2019\/01\/50411450_2222764207746758_1547410269309763584_o.jpg","datePublished":"2019-01-17T16:56:25+00:00","author":{"@id":"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sboverseas.org\/nl\/urgent-call-arsal-storm-crisis\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/sboverseas.org\/nl\/urgent-call-arsal-storm-crisis\/#primaryimage","url":"https:\/\/sboverseas.org\/wp-content\/uploads\/2019\/01\/50411450_2222764207746758_1547410269309763584_o.jpg","contentUrl":"https:\/\/sboverseas.org\/wp-content\/uploads\/2019\/01\/50411450_2222764207746758_1547410269309763584_o.jpg","width":1068,"height":712},{"@type":"WebSite","@id":"https:\/\/sboverseas.org\/#website","url":"https:\/\/sboverseas.org\/","name":"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","description":"Give Hope","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sboverseas.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Person","@id":"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/sboverseas.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/sboverseas.org"],"url":"https:\/\/sboverseas.org\/fr\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts\/5150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/comments?post=5150"}],"version-history":[{"count":0,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts\/5150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/media\/5154"}],"wp:attachment":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/media?parent=5150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/categories?post=5150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/tags?post=5150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}