{"id":4135,"date":"2018-09-28T12:01:01","date_gmt":"2018-09-28T10:01:01","guid":{"rendered":"https:\/\/sboverseas.org\/?p=4135"},"modified":"2018-09-28T12:01:01","modified_gmt":"2018-09-28T10:01:01","slug":"just-married-lhistoire-de-fatima-2","status":"publish","type":"post","link":"https:\/\/sboverseas.org\/fr\/just-married-lhistoire-de-fatima-2\/","title":{"rendered":"\u00ab Just Married \u00bb : l&#039;histoire de Fatima"},"content":{"rendered":"<p>Depuis le d\u00e9but de l&#039;ann\u00e9e, nous vous racontons les histoires que nous entendons sur le terrain \u00e0 proposer de la pratique du mariage des enfants ? Cela a commenc\u00e9 quand notre directrice s&#039;est rendue au Liban en septembre et s&#039;est fait servir <a href=\"https:\/\/sboverseas.org\/fr\/2018\/01\/17\/une-tasse-de-the-servie-par-des-epouses-enfants\/\">une tasse de th\u00e9 par une fille mari\u00e9e<\/a>.<\/p>\n<p>ce moment, SB OverSeas est d\u00e9termin\u00e9 \u00e0 Depuis attirer l&#039;attention sur le sujet en \u00e9crivant des <a href=\"https:\/\/sboverseas.org\/fr\/what-we-do\/advocacy\/\">histoires<\/a>, en publiant des articles et en parlant \u00e0 des <a href=\"https:\/\/sboverseas.org\/fr\/2018\/06\/27\/le-mariage-des-enfants-dans-les-communautes-de-refugies-une-reponse-desesperee-en-reponse-a-des-circonstances-desesperees\/\">\u00e9vent<\/a>.<\/p>\n<p>Comme nous vous l&#039;avons annonc\u00e9 en septembre, nous venons de commencer une s\u00e9rie de BD, cr\u00e9\u00e9es par F\u00e9lix Brassier pour nous faire partie de cette nouvelle vision que nous avons dans la vie et les exp\u00e9riences de ces filles. Nous avons le plaisir de lancer notre premi\u00e8re BD dans le cadre de ceci : l&#039;histoire de Fatima.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/online.fliphtml5.com\/njli\/desm\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4145 size-full\" src=\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/09\/story1-Fatima-French-LQ.jpg\" alt=\"\" width=\"918\" height=\"13897\"><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Depuis le d\u00e9but de l\u2019ann\u00e9e, nous vous racontons les histoires que nous entendons sur le terrain \u00e0 propos de la pratique du mariage des enfants&nbsp;? Cela a commenc\u00e9 quand notre directrice s\u2019est rendue au Liban en septembre et s\u2019est fait servir une tasse de th\u00e9 par une fille mari\u00e9e. Depuis ce moment, SB OverSeas est [&hellip;]<\/p>","protected":false},"author":162,"featured_media":4150,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[186,88,130],"tags":[154,190,59],"class_list":["post-4135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandes-dessinees-pour-enfants","category-communiques-de-presse","category-fr-plaidoyer","tag-child-marriage","tag-comic","tag-lebanon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00ab\u00a0Just Married\u00a0\u00bb\u00a0: l\u2019histoire de Fatima - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sboverseas.org\/fr\/just-married-lhistoire-de-fatima-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00ab\u00a0Just Married\u00a0\u00bb\u00a0: l\u2019histoire de Fatima - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"og:description\" content=\"Depuis le d\u00e9but de l\u2019ann\u00e9e, nous vous racontons les histoires que nous entendons sur le terrain \u00e0 propos de la pratique du mariage des enfants&nbsp;? Cela a commenc\u00e9 quand notre directrice s\u2019est rendue au Liban en septembre et s\u2019est fait servir une tasse de th\u00e9 par une fille mari\u00e9e. Depuis ce moment, SB OverSeas est [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sboverseas.org\/fr\/just-married-lhistoire-de-fatima-2\/\" \/>\n<meta property=\"og:site_name\" content=\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-28T10:01:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/09\/Screenshot-2018-09-28-11.54.18.png\" \/>\n\t<meta property=\"og:image:width\" content=\"333\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sboverseas.org\/just-married-lhistoire-de-fatima-2\/\",\"url\":\"https:\/\/sboverseas.org\/just-married-lhistoire-de-fatima-2\/\",\"name\":\"\u00ab\u00a0Just Married\u00a0\u00bb\u00a0: l\u2019histoire de Fatima - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"isPartOf\":{\"@id\":\"https:\/\/sboverseas.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sboverseas.org\/just-married-lhistoire-de-fatima-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sboverseas.org\/just-married-lhistoire-de-fatima-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/09\/Screenshot-2018-09-28-11.54.18.png\",\"datePublished\":\"2018-09-28T10:01:01+00:00\",\"author\":{\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sboverseas.org\/just-married-lhistoire-de-fatima-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/sboverseas.org\/just-married-lhistoire-de-fatima-2\/#primaryimage\",\"url\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/09\/Screenshot-2018-09-28-11.54.18.png\",\"contentUrl\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/09\/Screenshot-2018-09-28-11.54.18.png\",\"width\":333,\"height\":530},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sboverseas.org\/#website\",\"url\":\"https:\/\/sboverseas.org\/\",\"name\":\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"description\":\"Give Hope\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sboverseas.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sboverseas.org\"],\"url\":\"https:\/\/sboverseas.org\/fr\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00ab\u00a0Just Married\u00a0\u00bb\u00a0: l\u2019histoire de Fatima - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sboverseas.org\/fr\/just-married-lhistoire-de-fatima-2\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00ab\u00a0Just Married\u00a0\u00bb\u00a0: l\u2019histoire de Fatima - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","og_description":"Depuis le d\u00e9but de l\u2019ann\u00e9e, nous vous racontons les histoires que nous entendons sur le terrain \u00e0 propos de la pratique du mariage des enfants&nbsp;? Cela a commenc\u00e9 quand notre directrice s\u2019est rendue au Liban en septembre et s\u2019est fait servir une tasse de th\u00e9 par une fille mari\u00e9e. Depuis ce moment, SB OverSeas est [&hellip;]","og_url":"https:\/\/sboverseas.org\/fr\/just-married-lhistoire-de-fatima-2\/","og_site_name":"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","article_published_time":"2018-09-28T10:01:01+00:00","og_image":[{"width":333,"height":530,"url":"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/09\/Screenshot-2018-09-28-11.54.18.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture est.":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sboverseas.org\/just-married-lhistoire-de-fatima-2\/","url":"https:\/\/sboverseas.org\/just-married-lhistoire-de-fatima-2\/","name":"\u00ab\u00a0Just Married\u00a0\u00bb\u00a0: l\u2019histoire de Fatima - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","isPartOf":{"@id":"https:\/\/sboverseas.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sboverseas.org\/just-married-lhistoire-de-fatima-2\/#primaryimage"},"image":{"@id":"https:\/\/sboverseas.org\/just-married-lhistoire-de-fatima-2\/#primaryimage"},"thumbnailUrl":"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/09\/Screenshot-2018-09-28-11.54.18.png","datePublished":"2018-09-28T10:01:01+00:00","author":{"@id":"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sboverseas.org\/just-married-lhistoire-de-fatima-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/sboverseas.org\/just-married-lhistoire-de-fatima-2\/#primaryimage","url":"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/09\/Screenshot-2018-09-28-11.54.18.png","contentUrl":"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/09\/Screenshot-2018-09-28-11.54.18.png","width":333,"height":530},{"@type":"WebSite","@id":"https:\/\/sboverseas.org\/#website","url":"https:\/\/sboverseas.org\/","name":"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","description":"Give Hope","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sboverseas.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Person","@id":"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/sboverseas.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/sboverseas.org"],"url":"https:\/\/sboverseas.org\/fr\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts\/4135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/comments?post=4135"}],"version-history":[{"count":0,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts\/4135\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/media\/4150"}],"wp:attachment":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/media?parent=4135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/categories?post=4135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/tags?post=4135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}