{"id":3553,"date":"2018-07-04T10:50:06","date_gmt":"2018-07-04T08:50:06","guid":{"rendered":"https:\/\/sboverseas.org\/?p=3553"},"modified":"2018-07-04T10:50:06","modified_gmt":"2018-07-04T08:50:06","slug":"benevolat-au-liban-lhistoire-dalex","status":"publish","type":"post","link":"https:\/\/sboverseas.org\/fr\/benevolat-au-liban-lhistoire-dalex\/","title":{"rendered":"Benevolat au Liban: L&#039;histoire d&#039;Alex"},"content":{"rendered":"<p><strong>A propos de vous\u2026<\/strong><\/p>\n<p>Bonjour tout le monde ! Je suis Alex, je viens de Roumanie, et j&#039;ai travaill\u00e9 pendant cinq ans dans le secteur des croisi\u00e8res o\u00f9 j&#039;organisais surtout des visites. L&#039;an dernier, je me suis int\u00e9gr\u00e9 dans le freelance. Pour cela, j&#039;ai voyag\u00e9 en Egypte, en Iran et au Liban, o\u00f9 j&#039;ai appris l&#039;anglais, j&#039;ai \u00e9crit et dans\u00e9 et j&#039;ai go\u00fbt\u00e9 et pu d\u00e9couvrir de nouvelles choses et diff\u00e9rentes cultures. Cela m&#039;a permis de mieux me conna\u00eetre.<\/p>\n<p><strong>Comment avez-vous pris part au programme de SB ?<\/strong><\/p>\n<p>J&#039;ai d\u00e9couvert SB sur internet, je voulais vraiment travailler avec les r\u00e9fugi\u00e9s et j&#039;ai toujours voulu visiter le Liban !<\/p>\n<p><strong>Meilleur souvenir avec SB ?<\/strong><\/p>\n<p>C&#039;est \u00e9videmment l&#039;excursion en montagne ! C&#039;\u00e9tait un voyage organis\u00e9 pour les enfants de ma classe. Nous avons vu les C\u00e8dres de Dieu dans les montagnes Bsharri o\u00f9 la plupart des enfants ont vu et eu leur premi\u00e8re exp\u00e9rience avec la neige. Nous avons dans\u00e9, organis\u00e9 des batailles de boules de neige et contempl\u00e9 la beaut\u00e9 de l&#039;endroit o\u00f9 nous \u00e9tions. Ce souvenir est inoubliable. De plus, sur le chemin du retour, la plupart des b\u00e9n\u00e9voles et organisateurs \u00e9taient fatigu\u00e9s, et cela a \u00e9t\u00e9 incroyable de voir que les enfants continuaient de danser, chanter et sauter dans le bus avec la musique \u00e0 plein r\u00e9gime, comme s&#039;ils voulaient profiter de chaque miette de ces instants, comme s&#039;ils ne pensent jamais qu&#039;ils se terminent.<\/p>\n<p><strong>Qu&#039;est-ce qui a \u00e9t\u00e9 plus compliqu\u00e9 ?<\/strong><\/p>\n<p>Pour moi, il a \u00e9t\u00e9 assez difficile de g\u00e9rer les enfants qui n&#039;\u00e9taient pas destin\u00e9s \u00e0 l&#039;id\u00e9e de participer. Ceux qui souhaitaient rester \u00e0 l&#039;\u00e9cart ou refusaient de participer \u00e0 une activit\u00e9, un jeu ou un exercice. Il a aussi \u00e9t\u00e9 compliqu\u00e9 de travailler avec les enfants qui n&#039;avaient jamais \u00e9t\u00e9 dans un environnement scolaire. On se doit d&#039;\u00eatre patient et de prendre du temps pour se calmer pour r\u00e9pondre aux besoins de chacun et s&#039;habituer aux diff\u00e9rentes habitudes de vie.<\/p>\n<p><strong>Un conseil pour de futurs b\u00e9n\u00e9voles ?<\/strong><\/p>\n<p>Je pense que l&#039;approche que chaque b\u00e9n\u00e9vole devrait avoir dans ce contexte serait un camarade qui veut aider et partager, car ainsi, vous pouvez cr\u00e9er un environnement propice \u00e0 l&#039;apprentissage. L&#039;id\u00e9e pr\u00e9con\u00e7ue qu&#039;est l&#039;\u00e9ducation est diff\u00e9rente quand vous \u00eates dans un endroit avec le contexte d&#039;un camp de r\u00e9fugi\u00e9s. Nous devons tous faire de notre mieux et apprendre quelque chose chaque jour des autres. Aussi, je vous conseille d&#039;\u00eatre flexible et plein d&#039;humour, n&#039;h\u00e9sitez pas \u00e0 utiliser la musique, l&#039;espi\u00e8glerie et diverses activit\u00e9s.<\/p>\n<p><strong>Cela a-t-il chang\u00e9 votre vie d&#039;une certaine fa\u00e7on ?<\/strong><\/p>\n<p>Travailler avec des personnes qui ont perdu leur mode de vie, l&#039;endroit o\u00f9 ils vivaient, et parfois aussi des \u00eatres chers, leur enfance\u2026 tout cela a chang\u00e9 la personne que je suis. J&#039;ai compris que je devrais \u00eatre reconnaissante pour ce que j&#039;ai et c&#039;est en fait le seul moyen d&#039;\u00eatre capable d&#039;aider les gens \u00e0 affronter leurs difficult\u00e9s. J&#039;ai eu \u00e9norm\u00e9ment d&#039;admiration pour beaucoup de personnes \u2013 des hommes, des femmes et des enfants \u2013 qui ont eu tellement de volont\u00e9 et une attitude digne vis-\u00e0-vis de la vie alors qu&#039;ils sont pass\u00e9s par tellement de choses \u2026<\/p>\n<p>J&#039;ai d\u00e9cid\u00e9 de plus travailler avec des femmes \u2013 de m&#039;impliquer ou m\u00eame de cr\u00e9er un programme d&#039;autonomisation de femmes. J&#039;ai ressenti beaucoup de joie lorsque j&#039;ai organis\u00e9 les cours de fitness et je voudrais voir o\u00f9 cela me m\u00e8ne.<\/p>\n<p><strong>Quelle est la le\u00e7on la plus importante que vous avez retenue ?<\/strong><\/p>\n<p>La plus importante le\u00e7on que j&#039;ai retenue que nous avons le pouvoir de choisir et de faire la diff\u00e9rence pour des personnes qui en ont besoin en ce moment \u2013 plus que personne. Il y a de nombreuses causes \u00e0 d\u00e9fendre, c&#039;est vrai, mais je pense que l&#039;\u00e9ducation est le meilleur espoir que nous pouvons donner pour apporter du changement \u00e0 ce monde.<\/p>\n<p>Au final, il faut se demander \u2013 \u00e0 quel point les humains que nous sommes sont responsables de ce qui se passe aujourd&#039;hui dans le monde ? Et je pense que nous devrions regarder au-del\u00e0 de nos propres d\u00e9fis communs et ordinaires et juste chercher \u00e0 donner notre temps, notre attention, notre (non)exp\u00e9rience et bonne intention. Donnez.<\/p>\n<p><strong>Quelque chose que vous voulez partager ?<\/strong><\/p>\n<p>Les gens ont tendance \u00e0 compliquer les choses. Jouez-l\u00e0 simplement. Nous oublions souvent qu&#039;en \u00e9coutant les gens, en t\u00e9moignant notre reconnaissance ou m\u00eame en souriant, nous apportons des actes de gentillesse dans ce monde. C&#039;est peut-\u00eatre un clich\u00e9, mais peu importe : quand on veut on peut. Comme le dit un vieux proverbe : \u00ab c&#039;est la pluie qui fait pousser les fleurs, pas le tonnerre \u00bb.<\/p>\n<p><em>Lisez-en plus que les aventures d&#039;Alex sur son blog <a href=\"http:\/\/alexandrah.org\">ici<\/a> o\u00f9 elle \u00e9crit \u00e0 propos de ses exp\u00e9riences et de son b\u00e9n\u00e9volat au Liban.<\/em><\/p>\n<p><em>Int\u00e9ress\u00e9 par notre programme de b\u00e9n\u00e9volat au Liban ? Cliquez <a href=\"https:\/\/sboverseas.org\/fr\/volunteer\/lebanon\/\">ici<\/a> pour postuler !<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>A propos de vous \u2026 Bonjour tout le monde ! Je suis Alex, je viens de Roumanie, et j\u2019ai travaill\u00e9 pendant cinq ans dans le secteur des croisi\u00e8res o\u00f9 j\u2019organisais surtout des visites. L\u2019an dernier, je me suis lanc\u00e9e dans le freelance. Pour cela, j\u2019ai voyag\u00e9 en Egypte, en Iran et au Liban, o\u00f9 j\u2019ai [&hellip;]<\/p>","protected":false},"author":162,"featured_media":3517,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[181],"tags":[],"class_list":["post-3553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fr-benevoles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Benevolat au Liban: L&#039;histoire d&#039;Alex - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sboverseas.org\/fr\/benevolat-au-liban-lhistoire-dalex\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Benevolat au Liban: L&#039;histoire d&#039;Alex - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"og:description\" content=\"A propos de vous \u2026 Bonjour tout le monde ! Je suis Alex, je viens de Roumanie, et j\u2019ai travaill\u00e9 pendant cinq ans dans le secteur des croisi\u00e8res o\u00f9 j\u2019organisais surtout des visites. L\u2019an dernier, je me suis lanc\u00e9e dans le freelance. Pour cela, j\u2019ai voyag\u00e9 en Egypte, en Iran et au Liban, o\u00f9 j\u2019ai [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sboverseas.org\/fr\/benevolat-au-liban-lhistoire-dalex\/\" \/>\n<meta property=\"og:site_name\" content=\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-04T08:50:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/IMG_20180312_092116.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sboverseas.org\/benevolat-au-liban-lhistoire-dalex\/\",\"url\":\"https:\/\/sboverseas.org\/benevolat-au-liban-lhistoire-dalex\/\",\"name\":\"Benevolat au Liban: L'histoire d'Alex - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"isPartOf\":{\"@id\":\"https:\/\/sboverseas.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sboverseas.org\/benevolat-au-liban-lhistoire-dalex\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sboverseas.org\/benevolat-au-liban-lhistoire-dalex\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/IMG_20180312_092116.jpg\",\"datePublished\":\"2018-07-04T08:50:06+00:00\",\"author\":{\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sboverseas.org\/benevolat-au-liban-lhistoire-dalex\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/sboverseas.org\/benevolat-au-liban-lhistoire-dalex\/#primaryimage\",\"url\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/IMG_20180312_092116.jpg\",\"contentUrl\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/IMG_20180312_092116.jpg\",\"width\":1280,\"height\":960,\"caption\":\"dav\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sboverseas.org\/#website\",\"url\":\"https:\/\/sboverseas.org\/\",\"name\":\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"description\":\"Give Hope\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sboverseas.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sboverseas.org\"],\"url\":\"https:\/\/sboverseas.org\/fr\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Benevolat au Liban: L'histoire d'Alex - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sboverseas.org\/fr\/benevolat-au-liban-lhistoire-dalex\/","og_locale":"fr_FR","og_type":"article","og_title":"Benevolat au Liban: L'histoire d'Alex - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","og_description":"A propos de vous \u2026 Bonjour tout le monde ! Je suis Alex, je viens de Roumanie, et j\u2019ai travaill\u00e9 pendant cinq ans dans le secteur des croisi\u00e8res o\u00f9 j\u2019organisais surtout des visites. L\u2019an dernier, je me suis lanc\u00e9e dans le freelance. Pour cela, j\u2019ai voyag\u00e9 en Egypte, en Iran et au Liban, o\u00f9 j\u2019ai [&hellip;]","og_url":"https:\/\/sboverseas.org\/fr\/benevolat-au-liban-lhistoire-dalex\/","og_site_name":"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","article_published_time":"2018-07-04T08:50:06+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/IMG_20180312_092116.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture est.":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sboverseas.org\/benevolat-au-liban-lhistoire-dalex\/","url":"https:\/\/sboverseas.org\/benevolat-au-liban-lhistoire-dalex\/","name":"Benevolat au Liban: L'histoire d'Alex - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","isPartOf":{"@id":"https:\/\/sboverseas.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sboverseas.org\/benevolat-au-liban-lhistoire-dalex\/#primaryimage"},"image":{"@id":"https:\/\/sboverseas.org\/benevolat-au-liban-lhistoire-dalex\/#primaryimage"},"thumbnailUrl":"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/IMG_20180312_092116.jpg","datePublished":"2018-07-04T08:50:06+00:00","author":{"@id":"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sboverseas.org\/benevolat-au-liban-lhistoire-dalex\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/sboverseas.org\/benevolat-au-liban-lhistoire-dalex\/#primaryimage","url":"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/IMG_20180312_092116.jpg","contentUrl":"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/IMG_20180312_092116.jpg","width":1280,"height":960,"caption":"dav"},{"@type":"WebSite","@id":"https:\/\/sboverseas.org\/#website","url":"https:\/\/sboverseas.org\/","name":"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","description":"Give Hope","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sboverseas.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Person","@id":"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/sboverseas.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/sboverseas.org"],"url":"https:\/\/sboverseas.org\/fr\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts\/3553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/comments?post=3553"}],"version-history":[{"count":0,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts\/3553\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/media\/3517"}],"wp:attachment":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/media?parent=3553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/categories?post=3553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/tags?post=3553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}