{"id":2421,"date":"2016-12-03T15:54:52","date_gmt":"2016-12-03T14:54:52","guid":{"rendered":"https:\/\/sboverseas.org\/?p=2421"},"modified":"2016-12-03T15:54:52","modified_gmt":"2016-12-03T14:54:52","slug":"entre-lecole-et-la-mer-une-visite-au-camp-de-shatila","status":"publish","type":"post","link":"https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/","title":{"rendered":"Entre l&#039;\u00e9cole et la mer : une visite au camp de Chatila"},"content":{"rendered":"<p>Aux fen\u00eatres de l&#039;appartement des volontaires SB OverSeas, donnant sur la partie occidentale de Beyrouth, on peut avoir une vue de l&#039;ensemble de l&#039;\u00e9talement d\u00e9sordonn\u00e9 du camp de r\u00e9fugi\u00e9s de Chatila, entre l&#039;\u00e9cole et la mer. Ses niveaux et ses terrasses sont irr\u00e9guliers, les rues recouvertes de c\u00e2bles \u00e9lectriques et de canalisations, et les fen\u00eatres sans vitres donnent sur de sombres couloirs carrel\u00e9s parmi des b\u00e2timents de 12 \u00e9tages.<\/p>\n<p>Le 22 novembre \u2013 un jour f\u00e9ri\u00e9 pour comm\u00e9morer l&#039;ind\u00e9pendance du Liban \u2013 le personnel de SB OverSeas qui travaille dans le centre Bukra Ahla a d\u00e9cid\u00e9 de visiter les enfants individuellement et de visiter leurs maisons pour \u00e9valuer leurs conditions de vie et obtenir des informations quant aux besoins de leurs familles. Une tache de grande valeur, mais pour les volontaires qui enseignent \u00e0 l&#039;\u00e9cole, ce fut une exp\u00e9rience pr\u00e9cieuse pour une autre raison. Ils ont pu avoir un aper\u00e7u extraordinaire des vies des enfants avec qui ils avaient pass\u00e9 de nombreuses heures. Leurs attitudes joueuses, provocatrices, affectueuses ou silencieuses donnaient des indices sur leurs vies en dehors des cours.<\/p>\n<p>J&#039;ai parl\u00e9 de ce projet \u00e0 un ami et sa premi\u00e8re pr\u00e9occupation a \u00e9t\u00e9 que les enfants auraient \u00e9t\u00e9 g\u00ean\u00e9s de nous avoir dans leurs maisons, dont l&#039;aspect variait du modeste au sordide. Au contraire, les enfants nous ont conduits \u00e0 traverser leur quartier labyrinthique avec un air d&#039;insouciance, malgr\u00e9 la vigilance que le lieu exige. Les odeurs du march\u00e9 qui fument au nez, la cacophonie des scooters, des moteurs, des cages de perroquets et des cris qui entourent leurs maisons ne semblaient pas d\u00e9sorienter les enfants.<\/p>\n<p>Dans leurs salons, certains accessibles seulement \u00e0 travers une s\u00e9quence de sombre, escaliers pr\u00e9caires et passages \u00e9troits parmi les blocs de b\u00e9ton, ils \u00e9liminaient des grimaces et jouaient comme n&#039;importe quel enfant devant son prof\u00e9sseur buvant du th\u00e9 face \u00e0 ses parents. Dans certaines maisons il y avait jusqu&#039;\u00e0 dix ou douze personnes vivant dans deux pi\u00e8ces, avec une toilette sans ventilation pr\u00e8s de la cuisine.<\/p>\n<p>Aux \u00e9tages sup\u00e9rieurs, certaines pi\u00e8ces \u00e9taient recouvertes seulement par un morceau de t\u00f4le ondul\u00e9e, sans \u00e9lectricit\u00e9 ou protection contre la pluie. Dans les formulaires que nous devions remplir pour chaque famille, il y avait une section pour la description des cas m\u00e9dicaux des membres de la famille et des m\u00e9dicaments requis. Bien s\u00fbr, dans un environnement o\u00f9 l&#039;aire est lourde de pollution provenant de vastes d\u00e9charges, o\u00f9 le travail manuel se passe dans des ateliers et garages dont la surface est recouverte d&#039;une couche de quelconque, nos coll\u00e8gues arabophones ne r\u00e9v\u00e8lent qu&#039; annoter des d\u00e9tails de probl\u00e8mes respiratoires et des conditions cardiaques.<\/p>\n<p>Un p\u00e8re, confront\u00e9 \u00e0 la question de la sant\u00e9 de sa famille, a \u00e9cart\u00e9 la frange de sa petite fille pour nous montrer la brulure irr\u00e9parable sur une large moiti\u00e9 de son visage.<\/p>\n<p>Nous sommes pass\u00e9s \u00e0 c\u00f4t\u00e9 d&#039;une d\u00e9charge dans une section vide d&#039;un b\u00e2timent d\u00e9moli, o\u00f9 nous nous trouvions face \u00e0 une \u00e9quipe bizarre de pilleurs de poubelle \u2013 une dinde, un paon et une petite fille de 4 ans, qui \u00e9taient en train de feuilleter parmi les d\u00e9chets \u00e0 la recherche de quelque chose de r\u00e9utilisable ou amusant.<\/p>\n<p>La chose qui semblait la plus imp\u00e9n\u00e9trable \u00e0 l&#039;\u00e9tranger, parmi toutes les couleurs voyantes, les odeurs et les activit\u00e9s, \u00e9tait le sens de la communaut\u00e9. Comme d&#039;autres volontaires, je ne parle pas l&#039;arabe et il est difficile de comprendre enti\u00e8rement cette mani\u00e8re de cohabiter. Nous avons d\u00fb accepter la dimension sociale de la vie \u00e0 l&#039;int\u00e9rieur du camp entre voisins, amis et surement ennemis. C&#039;est un endroit dur et sale certes, mais l&#039;opportunit\u00e9 de le p\u00e9n\u00e9trer nous a permis de comprendre beaucoup plus sur nos gangs de filles et gar\u00e7ons ador\u00e9s.<\/p>","protected":false},"excerpt":{"rendered":"<p>Aux fen\u00eatres de l\u2019appartement des volontaires SB OverSeas, donnant sur la partie occidentale de Beyrouth, on peut avoir une vue de l\u2019ensemble de l&#8217;\u00e9talement d\u00e9sordonn\u00e9 du camp de r\u00e9fugi\u00e9s de Shatila, entre l\u2019\u00e9cole et la mer. Ses niveaux et ses terrasses sont irr\u00e9guliers, les rues recouvertes de c\u00e2bles \u00e9lectriques et de canalisations, et les fen\u00eatres [&hellip;]<\/p>","protected":false},"author":162,"featured_media":1470,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[87,88],"tags":[],"class_list":["post-2421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogs-de-benevoles","category-communiques-de-presse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entre l\u2019\u00e9cole et la mer : une visite au camp de Shatila - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entre l\u2019\u00e9cole et la mer : une visite au camp de Shatila - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"og:description\" content=\"Aux fen\u00eatres de l\u2019appartement des volontaires SB OverSeas, donnant sur la partie occidentale de Beyrouth, on peut avoir une vue de l\u2019ensemble de l&#8217;\u00e9talement d\u00e9sordonn\u00e9 du camp de r\u00e9fugi\u00e9s de Shatila, entre l\u2019\u00e9cole et la mer. Ses niveaux et ses terrasses sont irr\u00e9guliers, les rues recouvertes de c\u00e2bles \u00e9lectriques et de canalisations, et les fen\u00eatres [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/\" \/>\n<meta property=\"og:site_name\" content=\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-03T14:54:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sboverseas.org\/wp-content\/uploads\/2016\/12\/Shatila-e1511885375964.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/\",\"url\":\"https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/\",\"name\":\"Entre l\u2019\u00e9cole et la mer : une visite au camp de Shatila - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"isPartOf\":{\"@id\":\"https:\/\/sboverseas.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2016\/12\/Shatila-e1511885375964.jpg\",\"datePublished\":\"2016-12-03T14:54:52+00:00\",\"author\":{\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/#primaryimage\",\"url\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2016\/12\/Shatila-e1511885375964.jpg\",\"contentUrl\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2016\/12\/Shatila-e1511885375964.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sboverseas.org\/#website\",\"url\":\"https:\/\/sboverseas.org\/\",\"name\":\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"description\":\"Give Hope\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sboverseas.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sboverseas.org\"],\"url\":\"https:\/\/sboverseas.org\/fr\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entre l\u2019\u00e9cole et la mer : une visite au camp de Shatila - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/","og_locale":"fr_FR","og_type":"article","og_title":"Entre l\u2019\u00e9cole et la mer : une visite au camp de Shatila - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","og_description":"Aux fen\u00eatres de l\u2019appartement des volontaires SB OverSeas, donnant sur la partie occidentale de Beyrouth, on peut avoir une vue de l\u2019ensemble de l&#8217;\u00e9talement d\u00e9sordonn\u00e9 du camp de r\u00e9fugi\u00e9s de Shatila, entre l\u2019\u00e9cole et la mer. Ses niveaux et ses terrasses sont irr\u00e9guliers, les rues recouvertes de c\u00e2bles \u00e9lectriques et de canalisations, et les fen\u00eatres [&hellip;]","og_url":"https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/","og_site_name":"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","article_published_time":"2016-12-03T14:54:52+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/sboverseas.org\/wp-content\/uploads\/2016\/12\/Shatila-e1511885375964.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture est.":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/","url":"https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/","name":"Entre l\u2019\u00e9cole et la mer : une visite au camp de Shatila - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","isPartOf":{"@id":"https:\/\/sboverseas.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/#primaryimage"},"image":{"@id":"https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/#primaryimage"},"thumbnailUrl":"https:\/\/sboverseas.org\/wp-content\/uploads\/2016\/12\/Shatila-e1511885375964.jpg","datePublished":"2016-12-03T14:54:52+00:00","author":{"@id":"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/sboverseas.org\/fr\/entre-lecole-et-la-mer-une-visite-au-camp-de-shatila\/#primaryimage","url":"https:\/\/sboverseas.org\/wp-content\/uploads\/2016\/12\/Shatila-e1511885375964.jpg","contentUrl":"https:\/\/sboverseas.org\/wp-content\/uploads\/2016\/12\/Shatila-e1511885375964.jpg","width":1600,"height":1200},{"@type":"WebSite","@id":"https:\/\/sboverseas.org\/#website","url":"https:\/\/sboverseas.org\/","name":"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","description":"Give Hope","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sboverseas.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Person","@id":"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/sboverseas.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/sboverseas.org"],"url":"https:\/\/sboverseas.org\/fr\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts\/2421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/comments?post=2421"}],"version-history":[{"count":0,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts\/2421\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/media\/1470"}],"wp:attachment":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/media?parent=2421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/categories?post=2421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/tags?post=2421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}