{"id":20527,"date":"2020-03-02T16:33:19","date_gmt":"2020-03-02T15:33:19","guid":{"rendered":"https:\/\/sboverseas.org\/?p=20527"},"modified":"2020-03-02T16:33:19","modified_gmt":"2020-03-02T15:33:19","slug":"bringing-coding-games-to-asylum-seeking-youth","status":"publish","type":"post","link":"https:\/\/sboverseas.org\/fr\/bringing-coding-games-to-asylum-seeking-youth\/","title":{"rendered":"Apporter des jeux de codage aux jeunes demandeurs d&#039;asile"},"content":{"rendered":"<p><\/p>\n\n\n\n<p><em>&quot;Tout le monde devrait apprendre \u00e0 programmer un ordinateur, car cela vous apprend \u00e0 penser&quot; <br>\n\u2013Steve Jobs<\/em><\/p>\n\n\n\n<p>Comme dans les arts martiaux, la concentration et la discipline sont \u00e9galement deux des principaux \u00e9l\u00e9ments de l&#039;activit\u00e9 de codage. Au quotidien, nous utilisons une vari\u00e9t\u00e9 de programmes qui nous permettent d&#039;avoir une vie plus facile.&nbsp;<\/p>\n\n\n\n<p>Malheureusement, ce n&#039;est pas le cas partout dans le monde - de nombreux enfants et jeunes manquent encore de connaissances sur la technologie et son utilisation. Ainsi, avec l&#039;aide de CoderDojo, nous avons d\u00e9cid\u00e9 d&#039;offrir cette opportunit\u00e9 aux jeunes avec lesquels nous travaillons dans les centres, afin d&#039;ouvrir l&#039;horizon des jeunes \u00e0 \u00eatre cr\u00e9atifs avec la technologie de codage dans un environnement s\u00fbr et social.&nbsp;<\/p>\n\n\n\n<p>Le Centre Croix-Rouge d&#039;Uccle a \u00e9t\u00e9 le premier dans lequel notre initiative a \u00e9t\u00e9 mise en pratique. Au cours de cette activit\u00e9, les jeunes ont appris \u00e0 coder avec des ordinateurs et se sont familiaris\u00e9s avec certaines comp\u00e9tences informatiques avec l&#039;asbl CoderDojo et ses b\u00e9n\u00e9voles de BeCode.&nbsp;<\/p>\n\n\n\n<p>Les jeunes ont utilis\u00e9 un langage de codage pour cr\u00e9er des jeux. Dans la premi\u00e8re partie de la session, ils ont cod\u00e9 en utilisant uniquement les ordinateurs, alors que dans la deuxi\u00e8me partie de la session, ils ont attach\u00e9 \u00e0 leurs ordinateurs les micro bits. Les jeunes ont \u00e9t\u00e9 extr\u00eamement surpris lorsqu&#039;ils ont vu les petits morceaux de quincaillerie car ils n&#039;avaient jamais rencontr\u00e9 quelque chose comme \u00e7a auparavant. Par cons\u00e9quent, les b\u00e9n\u00e9voles de BeCode ont calmement expliqu\u00e9 ce que c&#039;est-<em> le Micro Bit est un syst\u00e8me embarqu\u00e9 bas\u00e9 sur ARM mat\u00e9riel open source con\u00e7u par la BBC pour une utilisation dans l&#039;enseignement de l&#039;informatique au Royaume-Uni.<\/em>\nPar la suite, les jeunes ont \u00e9t\u00e9 extr\u00eamement engag\u00e9s dans le codage tout en utilisant la nouvelle machine.&nbsp;<\/p>\n\n\n\n<p>Cette exp\u00e9rience leur a appris de nouvelles comp\u00e9tences et les a engag\u00e9s dans un autre type d&#039;activit\u00e9 qui pourrait leur \u00eatre b\u00e9n\u00e9fique \u00e0 long terme. Par ailleurs, un autre aspect positif de cette activit\u00e9 \u00e9tait qu&#039;elle contribuait \u00e0 l&#039;int\u00e9gration des jeunes nouvellement arriv\u00e9s en Belgique car ils n&#039;avaient jamais entendu parler de telles pratiques. C&#039;\u00e9tait un aspect tr\u00e8s important pour l&#039;\u00e9quipe de SB Espoir car nous sommes toujours impatients d&#039;engager les jeunes dans des activit\u00e9s \u00e9ducatives qui peuvent ouvrir leur perspective en ce qui concerne leurs perspectives de carri\u00e8re.&nbsp;<\/p>\n\n\n\n<p>Notre partenaire, CoderDojo a commenc\u00e9 aux \u00c9tats-Unis avec la simple question d&#039;un enfant face \u00e0 un hacker\u00a0: <em>&#039;comment avez-vous r\u00e9ussi \u00e0 avoir acc\u00e8s \u00e0 cette information?&#039;. <\/em>Ensuite, \u00e9tape par \u00e9tape, cette question a commenc\u00e9 \u00e0 avoir la r\u00e9ponse dans les cours CoderDojo. Au d\u00e9part, ceux-ci n&#039;\u00e9taient accessibles qu&#039;aux \u00c9tats-Unis, mais au fil des ans, ils se sont \u00e9tendus \u00e0 de nombreux autres coins du monde, comme la Belgique.&nbsp;&nbsp;<\/p>\n\n\n\n<p>En fin de journ\u00e9e, les jeunes pr\u00e9sents \u00e0 l&#039;activit\u00e9 nous ont dit qu&#039;ils \u00e9taient contents de rejoindre Dojo Coding et du coup ils voulaient suivre les cours les week-ends suivants au centre de codage.<\/p>\n\n\n\n<p>La technologie change rapidement le monde dans lequel nous vivons. Chaque jour, de nouvelles innovations sont d\u00e9velopp\u00e9es qui int\u00e8grent davantage la technologie dans notre vie quotidienne. Nous ne savons pas \u00e0 quoi ressemblera le monde dans 10 ans, mais nous savons que le monde sera propuls\u00e9 par l&#039;industrie informatique.&nbsp;<\/p>\n\n\n\n<p>Par cons\u00e9quent, il est essentiel de donner la chance \u00e0 chaque enfant jeune d&#039;avoir acc\u00e8s et de conna\u00eetre le pouvoir du codage. Avec CoderDojo, nous avons atteint notre objectif\u00a0!<\/p>\n\n\n\n<p><em>\u00c9crit par Diana Andrei, coordinatrice des activit\u00e9s SB Espoir<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>\u201cEverybody should learn to program a computer, because it teaches you how to think\u201d \u2013 Steve Jobs As in martial arts, focus and discipline are also two of the main elements when it comes to the activity of coding. On our everyday basis, we use a variety of programs which enables us to have an [&hellip;]<\/p>","protected":false},"author":162,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[137,45],"tags":[],"class_list":["post-20527","post","type-post","status-publish","format-standard","hentry","category-belgium","category-sb-espoir"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bringing coding games to asylum-seeking youth - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sboverseas.org\/fr\/bringing-coding-games-to-asylum-seeking-youth\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bringing coding games to asylum-seeking youth - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"og:description\" content=\"\u201cEverybody should learn to program a computer, because it teaches you how to think\u201d \u2013 Steve Jobs As in martial arts, focus and discipline are also two of the main elements when it comes to the activity of coding. On our everyday basis, we use a variety of programs which enables us to have an [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sboverseas.org\/fr\/bringing-coding-games-to-asylum-seeking-youth\/\" \/>\n<meta property=\"og:site_name\" content=\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-02T15:33:19+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sboverseas.org\/bringing-coding-games-to-asylum-seeking-youth\/\",\"url\":\"https:\/\/sboverseas.org\/bringing-coding-games-to-asylum-seeking-youth\/\",\"name\":\"Bringing coding games to asylum-seeking youth - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"isPartOf\":{\"@id\":\"https:\/\/sboverseas.org\/#website\"},\"datePublished\":\"2020-03-02T15:33:19+00:00\",\"author\":{\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sboverseas.org\/bringing-coding-games-to-asylum-seeking-youth\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sboverseas.org\/#website\",\"url\":\"https:\/\/sboverseas.org\/\",\"name\":\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"description\":\"Give Hope\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sboverseas.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sboverseas.org\"],\"url\":\"https:\/\/sboverseas.org\/fr\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bringing coding games to asylum-seeking youth - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sboverseas.org\/fr\/bringing-coding-games-to-asylum-seeking-youth\/","og_locale":"fr_FR","og_type":"article","og_title":"Bringing coding games to asylum-seeking youth - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","og_description":"\u201cEverybody should learn to program a computer, because it teaches you how to think\u201d \u2013 Steve Jobs As in martial arts, focus and discipline are also two of the main elements when it comes to the activity of coding. On our everyday basis, we use a variety of programs which enables us to have an [&hellip;]","og_url":"https:\/\/sboverseas.org\/fr\/bringing-coding-games-to-asylum-seeking-youth\/","og_site_name":"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","article_published_time":"2020-03-02T15:33:19+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture est.":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sboverseas.org\/bringing-coding-games-to-asylum-seeking-youth\/","url":"https:\/\/sboverseas.org\/bringing-coding-games-to-asylum-seeking-youth\/","name":"Bringing coding games to asylum-seeking youth - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","isPartOf":{"@id":"https:\/\/sboverseas.org\/#website"},"datePublished":"2020-03-02T15:33:19+00:00","author":{"@id":"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sboverseas.org\/bringing-coding-games-to-asylum-seeking-youth\/"]}]},{"@type":"WebSite","@id":"https:\/\/sboverseas.org\/#website","url":"https:\/\/sboverseas.org\/","name":"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire","description":"Give Hope","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sboverseas.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Person","@id":"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/sboverseas.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/sboverseas.org"],"url":"https:\/\/sboverseas.org\/fr\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts\/20527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/comments?post=20527"}],"version-history":[{"count":0,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/posts\/20527\/revisions"}],"wp:attachment":[{"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/media?parent=20527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/categories?post=20527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sboverseas.org\/fr\/wp-json\/wp\/v2\/tags?post=20527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}