{
    "id": 8740,
    "date": "2019-07-01T15:32:52",
    "date_gmt": "2019-07-01T13:32:52",
    "guid": {
        "rendered": "https:\/\/sboverseas.org\/?p=8740"
    },
    "modified": "2019-07-01T15:32:52",
    "modified_gmt": "2019-07-01T13:32:52",
    "slug": "que-se-passe-t-il-lorsque-plus-de-8-000-intellectuels-venus-du-monde-entier-se-reunissent-pour-repenser-les-programmes-de-developpement-de-lue",
    "status": "publish",
    "type": "post",
    "link": "https:\/\/sboverseas.org\/en\/que-se-passe-t-il-lorsque-plus-de-8-000-intellectuels-venus-du-monde-entier-se-reunissent-pour-repenser-les-programmes-de-developpement-de-lue\/",
    "title": {
        "rendered": "Que se passe-t-il lorsque plus de 8 000 intellectuels venus du monde entier se r\u00e9unissent pour repenser les programmes de d\u00e9veloppement de l&#8217;UE ?"
    },
    "content": {
        "rendered": "<p>La\nsemaine derni\u00e8re, l&#8217;\u00e9quipe SB a particip\u00e9 aux JED 2019, les Journ\u00e9es\nEurop\u00e9ennes du D\u00e9veloppement, qui portaient sur les\nnombreux moyens de rem\u00e9dier aux in\u00e9galit\u00e9s. Un grand nombre de conf\u00e9rences ont abord\u00e9 la n\u00e9cessit\u00e9\nde faire de l&#8217;\u00e9ducation le principal moteur d&#8217;une soci\u00e9t\u00e9 \u00e9galitaire et\npacifique. Toutefois, m\u00eame si les d\u00e9cideurs politiques s&#8217;accordent sur le fait\nque chaque enfant devrait \u00eatre scolaris\u00e9, le repr\u00e9sentant du Conseil de l&#8217;UE a\nd\u00e9clar\u00e9 que \u00ab les enfants ne figurent toujours pas dans la liste des priorit\u00e9s\npolitiques mondiales \u00bb. Plus de 260 millions d&#8217;enfants dans le monde ne vont\npas \u00e0 l\u2019\u00e9cole, un chiffre que l\u2019on devrait consid\u00e9rer comme une\npriorit\u00e9 mondiale imm\u00e9diate.<br>\n&nbsp;<br>\n<br>\nNotre organisation a su trouver les moyens d\u2019offrir un avenir et de l&#8217;espoir \u00e0 des milliers de r\u00e9fugi\u00e9s gr\u00e2ce \u00e0 la mise\nen place d&#8217;\u00e9coles informelles et de centres d&#8217;autonomisation, ainsi que par le biais de programmes d&#8217;inclusion sociale.\nNous sommes d&#8217;accord l\u2019un des pan\u00e9listes pr\u00e9sents, Feras Oyoun, r\u00e9fugi\u00e9 syrien ayant v\u00e9cu\nau Liban, lorsqu&#8217;il dit que &#8220;l&#8217;\u00e9ducation n&#8217;est pas un cadeau, lorsque nous\ndonnons ce droit, le droit \u00e0 l&#8217;\u00e9ducation, nous donnons la vie&#8221;. C\u2019est pour\ncette raison que le travail de SB Overseas \u00e0 Bruxelles et au Liban est essentiel.<br>\n<br>\nL&#8217;\u00e9quipe de Bruxelles a \u00e9galement donn\u00e9 une conf\u00e9rence aux stagiaires du\nParlement qui pourraient \u00e0 l\u2019avenir \u00eatre en charge de concevoir et de mettre en\n\u0153uvre les futures politiques de l&#8217;UE dans le monde, et qui deviendront\npeut-\u00eatre m\u00eame les futurs experts des\nprochaines \u00e9ditions des JED. En tant qu&#8217;ONG sur le terrain, nous pouvons\nsensibiliser et rapprocher ces jeunes dirigeants des besoins et des r\u00e9alit\u00e9s des\npopulations r\u00e9fugi\u00e9es, car la compr\u00e9hension des in\u00e9galit\u00e9s qui subsistent est\nla premi\u00e8re \u00e9tape vers la construction d&#8217;un monde o\u00f9 personne ne serait laiss\u00e9-pour-compte.<\/p>",
        "protected": false
    },
    "excerpt": {
        "rendered": "<p>La semaine derni\u00e8re, l&#8217;\u00e9quipe SB a particip\u00e9 aux JED 2019, les Journ\u00e9es Europ\u00e9ennes du D\u00e9veloppement, qui portaient sur les nombreux moyens de rem\u00e9dier aux in\u00e9galit\u00e9s. Un grand nombre de conf\u00e9rences ont abord\u00e9 la n\u00e9cessit\u00e9 de faire de l&#8217;\u00e9ducation le principal moteur d&#8217;une soci\u00e9t\u00e9 \u00e9galitaire et pacifique. Toutefois, m\u00eame si les d\u00e9cideurs politiques s&#8217;accordent sur le [&hellip;]<\/p>",
        "protected": false
    },
    "author": 162,
    "featured_media": 0,
    "comment_status": "open",
    "ping_status": "closed",
    "sticky": false,
    "template": "",
    "format": "standard",
    "meta": {
        "_et_pb_use_builder": "",
        "_et_pb_old_content": "",
        "_et_gb_content_width": "",
        "footnotes": ""
    },
    "categories": [
        136
    ],
    "tags": [],
    "class_list": [
        "post-8740",
        "post",
        "type-post",
        "status-publish",
        "format-standard",
        "hentry",
        "category-fr"
    ],
    "yoast_head": "<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Que se passe-t-il lorsque plus de 8 000 intellectuels venus du monde entier se r\u00e9unissent pour repenser les programmes de d\u00e9veloppement de l&#039;UE ? - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sboverseas.org\/en\/que-se-passe-t-il-lorsque-plus-de-8-000-intellectuels-venus-du-monde-entier-se-reunissent-pour-repenser-les-programmes-de-developpement-de-lue\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Que se passe-t-il lorsque plus de 8 000 intellectuels venus du monde entier se r\u00e9unissent pour repenser les programmes de d\u00e9veloppement de l&#039;UE ? - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"og:description\" content=\"La semaine derni\u00e8re, l&#8217;\u00e9quipe SB a particip\u00e9 aux JED 2019, les Journ\u00e9es Europ\u00e9ennes du D\u00e9veloppement, qui portaient sur les nombreux moyens de rem\u00e9dier aux in\u00e9galit\u00e9s. Un grand nombre de conf\u00e9rences ont abord\u00e9 la n\u00e9cessit\u00e9 de faire de l&#8217;\u00e9ducation le principal moteur d&#8217;une soci\u00e9t\u00e9 \u00e9galitaire et pacifique. Toutefois, m\u00eame si les d\u00e9cideurs politiques s&#8217;accordent sur le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sboverseas.org\/en\/que-se-passe-t-il-lorsque-plus-de-8-000-intellectuels-venus-du-monde-entier-se-reunissent-pour-repenser-les-programmes-de-developpement-de-lue\/\" \/>\n<meta property=\"og:site_name\" content=\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-01T13:32:52+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/sboverseas.org\/fr\/que-se-passe-t-il-lorsque-plus-de-8-000-intellectuels-venus-du-monde-entier-se-reunissent-pour-repenser-les-programmes-de-developpement-de-lue\/\",\"url\":\"http:\/\/sboverseas.org\/fr\/que-se-passe-t-il-lorsque-plus-de-8-000-intellectuels-venus-du-monde-entier-se-reunissent-pour-repenser-les-programmes-de-developpement-de-lue\/\",\"name\":\"Que se passe-t-il lorsque plus de 8 000 intellectuels venus du monde entier se r\u00e9unissent pour repenser les programmes de d\u00e9veloppement de l'UE ? - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"isPartOf\":{\"@id\":\"https:\/\/sboverseas.org\/#website\"},\"datePublished\":\"2019-07-01T13:32:52+00:00\",\"author\":{\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/sboverseas.org\/fr\/que-se-passe-t-il-lorsque-plus-de-8-000-intellectuels-venus-du-monde-entier-se-reunissent-pour-repenser-les-programmes-de-developpement-de-lue\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sboverseas.org\/#website\",\"url\":\"https:\/\/sboverseas.org\/\",\"name\":\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"description\":\"Give Hope\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sboverseas.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sboverseas.org\"],\"url\":\"https:\/\/sboverseas.org\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->",
    "yoast_head_json": {
        "title": "Que se passe-t-il lorsque plus de 8 000 intellectuels venus du monde entier se r\u00e9unissent pour repenser les programmes de d\u00e9veloppement de l'UE ? - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire",
        "robots": {
            "index": "index",
            "follow": "follow",
            "max-snippet": "max-snippet:-1",
            "max-image-preview": "max-image-preview:large",
            "max-video-preview": "max-video-preview:-1"
        },
        "canonical": "http:\/\/sboverseas.org\/en\/que-se-passe-t-il-lorsque-plus-de-8-000-intellectuels-venus-du-monde-entier-se-reunissent-pour-repenser-les-programmes-de-developpement-de-lue\/",
        "og_locale": "en_US",
        "og_type": "article",
        "og_title": "Que se passe-t-il lorsque plus de 8 000 intellectuels venus du monde entier se r\u00e9unissent pour repenser les programmes de d\u00e9veloppement de l'UE ? - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire",
        "og_description": "La semaine derni\u00e8re, l&#8217;\u00e9quipe SB a particip\u00e9 aux JED 2019, les Journ\u00e9es Europ\u00e9ennes du D\u00e9veloppement, qui portaient sur les nombreux moyens de rem\u00e9dier aux in\u00e9galit\u00e9s. Un grand nombre de conf\u00e9rences ont abord\u00e9 la n\u00e9cessit\u00e9 de faire de l&#8217;\u00e9ducation le principal moteur d&#8217;une soci\u00e9t\u00e9 \u00e9galitaire et pacifique. Toutefois, m\u00eame si les d\u00e9cideurs politiques s&#8217;accordent sur le [&hellip;]",
        "og_url": "http:\/\/sboverseas.org\/en\/que-se-passe-t-il-lorsque-plus-de-8-000-intellectuels-venus-du-monde-entier-se-reunissent-pour-repenser-les-programmes-de-developpement-de-lue\/",
        "og_site_name": "SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire",
        "article_published_time": "2019-07-01T13:32:52+00:00",
        "author": "admin",
        "twitter_card": "summary_large_image",
        "twitter_misc": {
            "Written by": "admin",
            "Est. reading time": "2 minutes"
        },
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "WebPage",
                    "@id": "http:\/\/sboverseas.org\/fr\/que-se-passe-t-il-lorsque-plus-de-8-000-intellectuels-venus-du-monde-entier-se-reunissent-pour-repenser-les-programmes-de-developpement-de-lue\/",
                    "url": "http:\/\/sboverseas.org\/fr\/que-se-passe-t-il-lorsque-plus-de-8-000-intellectuels-venus-du-monde-entier-se-reunissent-pour-repenser-les-programmes-de-developpement-de-lue\/",
                    "name": "Que se passe-t-il lorsque plus de 8 000 intellectuels venus du monde entier se r\u00e9unissent pour repenser les programmes de d\u00e9veloppement de l'UE ? - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire",
                    "isPartOf": {
                        "@id": "https:\/\/sboverseas.org\/#website"
                    },
                    "datePublished": "2019-07-01T13:32:52+00:00",
                    "author": {
                        "@id": "https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d"
                    },
                    "inLanguage": "en-US",
                    "potentialAction": [
                        {
                            "@type": "ReadAction",
                            "target": [
                                "http:\/\/sboverseas.org\/fr\/que-se-passe-t-il-lorsque-plus-de-8-000-intellectuels-venus-du-monde-entier-se-reunissent-pour-repenser-les-programmes-de-developpement-de-lue\/"
                            ]
                        }
                    ]
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/sboverseas.org\/#website",
                    "url": "https:\/\/sboverseas.org\/",
                    "name": "SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire",
                    "description": "Give Hope",
                    "potentialAction": [
                        {
                            "@type": "SearchAction",
                            "target": {
                                "@type": "EntryPoint",
                                "urlTemplate": "https:\/\/sboverseas.org\/?s={search_term_string}"
                            },
                            "query-input": {
                                "@type": "PropertyValueSpecification",
                                "valueRequired": true,
                                "valueName": "search_term_string"
                            }
                        }
                    ],
                    "inLanguage": "en-US"
                },
                {
                    "@type": "Person",
                    "@id": "https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d",
                    "name": "admin",
                    "image": {
                        "@type": "ImageObject",
                        "inLanguage": "en-US",
                        "@id": "https:\/\/sboverseas.org\/#\/schema\/person\/image\/",
                        "url": "https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g",
                        "contentUrl": "https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g",
                        "caption": "admin"
                    },
                    "sameAs": [
                        "https:\/\/sboverseas.org"
                    ],
                    "url": "https:\/\/sboverseas.org\/en\/author\/admin\/"
                }
            ]
        }
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/posts\/8740",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/posts"
            }
        ],
        "about": [
            {
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/types\/post"
            }
        ],
        "author": [
            {
                "embeddable": true,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/users\/162"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/comments?post=8740"
            }
        ],
        "version-history": [
            {
                "count": 0,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/posts\/8740\/revisions"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/media?parent=8740"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "category",
                "embeddable": true,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/categories?post=8740"
            },
            {
                "taxonomy": "post_tag",
                "embeddable": true,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/tags?post=8740"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}