{
    "id": 4001,
    "date": "2018-08-28T15:46:42",
    "date_gmt": "2018-08-28T13:46:42",
    "guid": {
        "rendered": "https:\/\/sboverseas.org\/?p=4001"
    },
    "modified": "2018-08-28T15:46:42",
    "modified_gmt": "2018-08-28T13:46:42",
    "slug": "just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens",
    "status": "publish",
    "type": "post",
    "link": "https:\/\/sboverseas.org\/en\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/",
    "title": {
        "rendered": "\u2018JUST MARRIED\u2019 (tout juste mari\u00e9s) : le mariage des enfants dans les communaut\u00e9s de r\u00e9fugi\u00e9s syriens"
    },
    "content": {
        "rendered": "<div class=\"\" data-block=\"true\" data-editor=\"j30i\" data-offset-key=\"b37as-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"b37as-0-0\"><span data-offset-key=\"b37as-0-0\"><span data-text=\"true\">Quand vous pensez \u00e0 \u00ab tout juste mari\u00e9s \u00bb, \u00e0 quoi pensez-vous ? Moi, je pense au message \u00e9crit sur l\u2019arri\u00e8re d\u2019une voiture conduite par deux personnes tout juste mari\u00e9es. Une pens\u00e9e positive, une journ\u00e9e heureuse pour commencer une nouvelle et belle vie. Tout ce qu\u2019un mariage, tant la c\u00e9r\u00e9monie que l\u2019institution, devrait repr\u00e9senter.<\/span><\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"j30i\" data-offset-key=\"6jkbd-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"6jkbd-0-0\"><span data-offset-key=\"6jkbd-0-0\">&nbsp;<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"j30i\" data-offset-key=\"5ppt8-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"5ppt8-0-0\"><span data-offset-key=\"5ppt8-0-0\"><span data-text=\"true\">N\u00e9anmoins, pour certains, cela n\u2019est pas la r\u00e9alit\u00e9. <\/span><\/span><span class=\"hardreadability\"><span data-offset-key=\"5ppt8-1-0\"><span data-text=\"true\">Dup\u00e9es par les r\u00eaves d\u2019un mariage digne d\u2019un conte de f\u00e9es, plusieurs de nos jeunes filles se l\u00e8vent un beau matin et se retrouvent \u00ab juste mari\u00e9es \u00bb<\/span><\/span><\/span><span data-offset-key=\"5ppt8-2-0\"><span data-text=\"true\">. Mari\u00e9e \u00e0 un homme de plusieurs ann\u00e9es de plus qu\u2019elle. Des attentes trop \u00e9lev\u00e9es p\u00e8sent alors sur ses \u00e9paules.<\/span><\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"j30i\" data-offset-key=\"c9ant-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"c9ant-0-0\"><span data-offset-key=\"c9ant-0-0\">&nbsp;<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"j30i\" data-offset-key=\"fqpj4-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"fqpj4-0-0\"><span data-offset-key=\"fqpj4-0-0\"><span data-text=\"true\">Durant ces derniers mois, nous avons partag\u00e9 un grand nombre de nos histoires. <\/span><\/span><span class=\"veryhardreadability\"><span data-offset-key=\"fqpj4-1-0\"><span data-text=\"true\">Des histoires de <a href=\"https:\/\/sboverseas.org\/en\/2018\/07\/25\/la-vie-quand-on-a-treize-ans-un-futur-vole\/\">jeunes filles de 13 ans <\/a>dont le futur a \u00e9t\u00e9 vol\u00e9, des filles battues simplement pour avoir demand\u00e9 du chocolat, des filles divorc\u00e9es laiss\u00e9es seules \u00e0 devoir prendre soin de leur enfant, alors qu\u2019elles-m\u00eames ne sont que des enfants, des histoires <a href=\"https:\/\/sboverseas.org\/en\/2018\/05\/18\/une-enfant-separee-de-son-enfant\/\">de celles s\u00e9par\u00e9es de leurs enfants<\/a><\/span><\/span><\/span><span data-offset-key=\"fqpj4-2-0\"><span data-text=\"true\">. <\/span><\/span><span class=\"veryhardreadability\"><span data-offset-key=\"fqpj4-3-0\"><span data-text=\"true\">Nous avons parl\u00e9 de ce probl\u00e8me au <a href=\"https:\/\/sboverseas.org\/en\/2018\/06\/27\/le-mariage-des-enfants-dans-les-communautes-de-refugies-une-reponse-desesperee-en-reponse-a-des-circonstances-desesperees\/\">Parlement Europ\u00e9en<\/a> et soulign\u00e9 l\u2019explosion des taux de mariages d\u2019enfants (de 13% \u00e0 42%) dans notre publication <a href=\"https:\/\/sboverseas.org\/en\/download\/3454\/\">\u00ab le mariage des enfants : des histoires sur le terrain \u00bb<\/a> ainsi que dans <a href=\"https:\/\/www.youtube.com\/watch?v=CROWrZtvMOI&amp;t=21s&amp;frags=pl%2Cwn\">la vid\u00e9o de Kevin Charbel<\/a><\/span><\/span><\/span><a href=\"https:\/\/www.youtube.com\/watch?v=CROWrZtvMOI&amp;t=21s&amp;frags=pl%2Cwn\"><span data-offset-key=\"fqpj4-4-0\"><span data-text=\"true\">.<\/span><\/span><\/a><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"j30i\" data-offset-key=\"7ni64-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"7ni64-0-0\"><span data-offset-key=\"7ni64-0-0\">&nbsp;<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"j30i\" data-offset-key=\"5b8bp-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"5b8bp-0-0\"><span data-offset-key=\"5b8bp-0-0\"><span data-text=\"true\">Maintenant, nous abordons le probl\u00e8me sous un nouvel angle. <\/span><\/span><span class=\"hardreadability\"><span data-offset-key=\"5b8bp-1-0\"><span data-text=\"true\">Nous publierons nos histoires de mariages des enfants mensuellement sous la forme d\u2019une BD<\/span><\/span><\/span><span data-offset-key=\"5b8bp-2-0\"><span data-text=\"true\">. <\/span><\/span><span class=\"veryhardreadability\"><span data-offset-key=\"5b8bp-3-0\"><span data-text=\"true\">Celle-ci sera dessin\u00e9e par notre talentueux F\u00e9lix Brassier, qui produit des vid\u00e9os pour nous, par exemple le documentaire sur <a href=\"https:\/\/www.youtube.com\/watch?v=YzHAcahNCxg\">Dan Thompson<\/a>, le coureur d\u2019Ersal qui a couru avec SB OverSeas, ou celle de <a href=\"https:\/\/www.youtube.com\/watch?v=wAdEwiER9hg\">nos \u00e9tudiants c\u00e9l\u00e9brant l\u2019A\u00efd Al-Adha<\/a><\/span><\/span><\/span><span data-offset-key=\"5b8bp-4-0\"><span data-text=\"true\">.<\/span><\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"j30i\" data-offset-key=\"gvbr-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"gvbr-0-0\"><span data-offset-key=\"gvbr-0-0\">&nbsp;<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"j30i\" data-offset-key=\"42kuv-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"42kuv-0-0\"><span data-offset-key=\"42kuv-0-0\"><span data-text=\"true\">Envie d\u2019y prendre part ? <\/span><\/span><span class=\"hardreadability\"><span data-offset-key=\"42kuv-1-0\"><span data-text=\"true\">Nous sommes \u00e0 la recherche de sponsors, de personnes pour publier notre BD et de toute autre personne ayant envie d\u2019attirer l\u2019attention sur ce probl\u00e8me<\/span><\/span><\/span><span data-offset-key=\"42kuv-2-0\"><span data-text=\"true\">. Envoyez un email \u00e0 Jade \u00e0 l\u2019adresse suivante : hq.communications@sboverseas.org<\/span><\/span><\/div>\n<\/div>",
        "protected": false
    },
    "excerpt": {
        "rendered": "<p>Quand vous pensez \u00e0 \u00ab tout juste mari\u00e9s \u00bb, \u00e0 quoi pensez-vous ? Moi, je pense au message \u00e9crit sur l\u2019arri\u00e8re d\u2019une voiture conduite par deux personnes tout juste mari\u00e9es. Une pens\u00e9e positive, une journ\u00e9e heureuse pour commencer une nouvelle et belle vie. Tout ce qu\u2019un mariage, tant la c\u00e9r\u00e9monie que l\u2019institution, devrait repr\u00e9senter. &nbsp; [&hellip;]<\/p>",
        "protected": false
    },
    "author": 162,
    "featured_media": 3994,
    "comment_status": "open",
    "ping_status": "closed",
    "sticky": false,
    "template": "",
    "format": "standard",
    "meta": {
        "_et_pb_use_builder": "",
        "_et_pb_old_content": "",
        "_et_gb_content_width": "",
        "footnotes": ""
    },
    "categories": [
        186,
        88
    ],
    "tags": [],
    "class_list": [
        "post-4001",
        "post",
        "type-post",
        "status-publish",
        "format-standard",
        "has-post-thumbnail",
        "hentry",
        "category-bandes-dessinees-pour-enfants",
        "category-communiques-de-presse"
    ],
    "yoast_head": "<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u2018JUST MARRIED\u2019 (tout juste mari\u00e9s) : le mariage des enfants dans les communaut\u00e9s de r\u00e9fugi\u00e9s syriens - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sboverseas.org\/en\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2018JUST MARRIED\u2019 (tout juste mari\u00e9s) : le mariage des enfants dans les communaut\u00e9s de r\u00e9fugi\u00e9s syriens - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"og:description\" content=\"Quand vous pensez \u00e0 \u00ab tout juste mari\u00e9s \u00bb, \u00e0 quoi pensez-vous ? Moi, je pense au message \u00e9crit sur l\u2019arri\u00e8re d\u2019une voiture conduite par deux personnes tout juste mari\u00e9es. Une pens\u00e9e positive, une journ\u00e9e heureuse pour commencer une nouvelle et belle vie. Tout ce qu\u2019un mariage, tant la c\u00e9r\u00e9monie que l\u2019institution, devrait repr\u00e9senter. &nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sboverseas.org\/en\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/\" \/>\n<meta property=\"og:site_name\" content=\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-28T13:46:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/08\/Designed-by-Felix-BrassierCopyright-\u00a9-2018-all-rights-reserved.-e1535463253906.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"141\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/sboverseas.org\/nl\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/\",\"url\":\"http:\/\/sboverseas.org\/nl\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/\",\"name\":\"\u2018JUST MARRIED\u2019 (tout juste mari\u00e9s) : le mariage des enfants dans les communaut\u00e9s de r\u00e9fugi\u00e9s syriens - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"isPartOf\":{\"@id\":\"https:\/\/sboverseas.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/sboverseas.org\/nl\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/sboverseas.org\/nl\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/08\/Designed-by-Felix-BrassierCopyright-\u00a9-2018-all-rights-reserved.-e1535463253906.jpg\",\"datePublished\":\"2018-08-28T13:46:42+00:00\",\"author\":{\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/sboverseas.org\/nl\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/sboverseas.org\/nl\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/#primaryimage\",\"url\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/08\/Designed-by-Felix-BrassierCopyright-\u00a9-2018-all-rights-reserved.-e1535463253906.jpg\",\"contentUrl\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/08\/Designed-by-Felix-BrassierCopyright-\u00a9-2018-all-rights-reserved.-e1535463253906.jpg\",\"width\":141,\"height\":200},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sboverseas.org\/#website\",\"url\":\"https:\/\/sboverseas.org\/\",\"name\":\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"description\":\"Give Hope\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sboverseas.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sboverseas.org\"],\"url\":\"https:\/\/sboverseas.org\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->",
    "yoast_head_json": {
        "title": "\u2018JUST MARRIED\u2019 (tout juste mari\u00e9s) : le mariage des enfants dans les communaut\u00e9s de r\u00e9fugi\u00e9s syriens - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire",
        "robots": {
            "index": "index",
            "follow": "follow",
            "max-snippet": "max-snippet:-1",
            "max-image-preview": "max-image-preview:large",
            "max-video-preview": "max-video-preview:-1"
        },
        "canonical": "http:\/\/sboverseas.org\/en\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/",
        "og_locale": "en_US",
        "og_type": "article",
        "og_title": "\u2018JUST MARRIED\u2019 (tout juste mari\u00e9s) : le mariage des enfants dans les communaut\u00e9s de r\u00e9fugi\u00e9s syriens - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire",
        "og_description": "Quand vous pensez \u00e0 \u00ab tout juste mari\u00e9s \u00bb, \u00e0 quoi pensez-vous ? Moi, je pense au message \u00e9crit sur l\u2019arri\u00e8re d\u2019une voiture conduite par deux personnes tout juste mari\u00e9es. Une pens\u00e9e positive, une journ\u00e9e heureuse pour commencer une nouvelle et belle vie. Tout ce qu\u2019un mariage, tant la c\u00e9r\u00e9monie que l\u2019institution, devrait repr\u00e9senter. &nbsp; [&hellip;]",
        "og_url": "http:\/\/sboverseas.org\/en\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/",
        "og_site_name": "SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire",
        "article_published_time": "2018-08-28T13:46:42+00:00",
        "og_image": [
            {
                "width": 141,
                "height": 200,
                "url": "https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/08\/Designed-by-Felix-BrassierCopyright-\u00a9-2018-all-rights-reserved.-e1535463253906.jpg",
                "type": "image\/jpeg"
            }
        ],
        "author": "admin",
        "twitter_card": "summary_large_image",
        "twitter_misc": {
            "Written by": "admin",
            "Est. reading time": "2 minutes"
        },
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "WebPage",
                    "@id": "http:\/\/sboverseas.org\/nl\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/",
                    "url": "http:\/\/sboverseas.org\/nl\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/",
                    "name": "\u2018JUST MARRIED\u2019 (tout juste mari\u00e9s) : le mariage des enfants dans les communaut\u00e9s de r\u00e9fugi\u00e9s syriens - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire",
                    "isPartOf": {
                        "@id": "https:\/\/sboverseas.org\/#website"
                    },
                    "primaryImageOfPage": {
                        "@id": "http:\/\/sboverseas.org\/nl\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/#primaryimage"
                    },
                    "image": {
                        "@id": "http:\/\/sboverseas.org\/nl\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/#primaryimage"
                    },
                    "thumbnailUrl": "https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/08\/Designed-by-Felix-BrassierCopyright-\u00a9-2018-all-rights-reserved.-e1535463253906.jpg",
                    "datePublished": "2018-08-28T13:46:42+00:00",
                    "author": {
                        "@id": "https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d"
                    },
                    "inLanguage": "en-US",
                    "potentialAction": [
                        {
                            "@type": "ReadAction",
                            "target": [
                                "http:\/\/sboverseas.org\/nl\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/"
                            ]
                        }
                    ]
                },
                {
                    "@type": "ImageObject",
                    "inLanguage": "en-US",
                    "@id": "http:\/\/sboverseas.org\/nl\/just-married-tout-juste-maries-le-mariage-des-enfants-dans-les-communautes-de-refugies-syriens\/#primaryimage",
                    "url": "https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/08\/Designed-by-Felix-BrassierCopyright-\u00a9-2018-all-rights-reserved.-e1535463253906.jpg",
                    "contentUrl": "https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/08\/Designed-by-Felix-BrassierCopyright-\u00a9-2018-all-rights-reserved.-e1535463253906.jpg",
                    "width": 141,
                    "height": 200
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/sboverseas.org\/#website",
                    "url": "https:\/\/sboverseas.org\/",
                    "name": "SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire",
                    "description": "Give Hope",
                    "potentialAction": [
                        {
                            "@type": "SearchAction",
                            "target": {
                                "@type": "EntryPoint",
                                "urlTemplate": "https:\/\/sboverseas.org\/?s={search_term_string}"
                            },
                            "query-input": {
                                "@type": "PropertyValueSpecification",
                                "valueRequired": true,
                                "valueName": "search_term_string"
                            }
                        }
                    ],
                    "inLanguage": "en-US"
                },
                {
                    "@type": "Person",
                    "@id": "https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d",
                    "name": "admin",
                    "image": {
                        "@type": "ImageObject",
                        "inLanguage": "en-US",
                        "@id": "https:\/\/sboverseas.org\/#\/schema\/person\/image\/",
                        "url": "https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g",
                        "contentUrl": "https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g",
                        "caption": "admin"
                    },
                    "sameAs": [
                        "https:\/\/sboverseas.org"
                    ],
                    "url": "https:\/\/sboverseas.org\/en\/author\/admin\/"
                }
            ]
        }
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/posts\/4001",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/posts"
            }
        ],
        "about": [
            {
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/types\/post"
            }
        ],
        "author": [
            {
                "embeddable": true,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/users\/162"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/comments?post=4001"
            }
        ],
        "version-history": [
            {
                "count": 0,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/posts\/4001\/revisions"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/media\/3994"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/media?parent=4001"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "category",
                "embeddable": true,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/categories?post=4001"
            },
            {
                "taxonomy": "post_tag",
                "embeddable": true,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/tags?post=4001"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}