{
    "id": 3752,
    "date": "2017-05-15T21:18:24",
    "date_gmt": "2017-05-15T19:18:24",
    "guid": {
        "rendered": "https:\/\/sboverseas.org\/?p=3752"
    },
    "modified": "2017-05-15T21:18:24",
    "modified_gmt": "2017-05-15T19:18:24",
    "slug": "sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles",
    "status": "publish",
    "type": "post",
    "link": "https:\/\/sboverseas.org\/en\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/",
    "title": {
        "rendered": "SB OVERSEAS ET LES EMPLOY\u00c9S DE PWC FONT LA DIFF\u00c9RENCE POUR LES JEUNES R\u00c9FUGI\u00c9S DE BRUXELLES"
    },
    "content": {
        "rendered": "<p>&nbsp;<\/p>\n<p>Un groupe d\u2019employ\u00e9s tr\u00e8s motiv\u00e9s de PricewaterhouseCoopers a propos\u00e9 d\u2019offrir de son temps lors d\u2019un dimanche apr\u00e8s-midi ensoleill\u00e9 pour faire du b\u00e9n\u00e9volat avec SB OverSeas et les jeunes r\u00e9fugi\u00e9s du centre d\u2019Uccle Croix-Rouge. Les employ\u00e9s de PwC de toute la Belgique sont venus avec les membres de leur famille pour prendre part aux activit\u00e9s et ont pass\u00e9 un bon moment, un si bon moment qu\u2019ils ont affirm\u00e9 leur engagement d\u2019y participer une seconde fois.<\/p>\n<p>Dans le cadre de la semaine \u00ab&nbsp;Ensemble nous faisons une plus grande diff\u00e9rence&nbsp;\u00bb, la semaine de b\u00e9n\u00e9volat annuelle de PwC, le cadre sup\u00e9rieur Damien Dierckx et son \u00e9quipe ont particip\u00e9 \u00e0 notre programme d\u2019\u00e9ducation et d\u2019int\u00e9gration \u00ab&nbsp;SB Weekend&nbsp;\u00bb pour les jeunes r\u00e9fugi\u00e9s non-accompagn\u00e9s qui leur permet de s\u2019ouvrir au monde et d\u2019accro\u00eetre leur sentiment d\u2019appartenance \u00e0 leur nouvelle soci\u00e9t\u00e9, \u00e0 travers un programme d\u2019activit\u00e9s artistiques et artisanales et d\u2019activit\u00e9s sportives.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>\n<p><a href=\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/image-3.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3754\" src=\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/image-3-300x200.png\" alt=\"image\" width=\"300\" height=\"200\"><\/a><\/p>\n<p>Nous avons accueilli les b\u00e9n\u00e9voles de SB OverSeas dans nos bureaux de Bruxelles avec un d\u00e9jeuner et une pr\u00e9sentation de nos programmes. A ce moment l\u00e0, les employ\u00e9s de PwC ont pris l\u2019engagement de nous aider \u00e0 remplir un conteneur de donations d\u2019habits destin\u00e9s aux r\u00e9fugi\u00e9s dans le Moyen-Orient.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>\n<p>Avec la directrice de SB OverSeas Louma Albik, le groupe a \u00e9t\u00e9 dans un parc pr\u00e8s du centre d\u2019Uccle Croix-Rouge o\u00f9 quatre des b\u00e9n\u00e9voles de SB OverSeas avaient d\u00e9j\u00e0 install\u00e9s le premier atelier de cr\u00e9ations artisanales. L\u2019\u00e9quipe et les jeunes r\u00e9fugi\u00e9s du centre ont ensemble d\u00fb cr\u00e9er des objets faits de carton sur le th\u00e8me de l\u2019hospitalit\u00e9. Leur travail a \u00e9t\u00e9 tr\u00e8s cr\u00e9atif, puisqu\u2019il a inclus des cr\u00e9ations de mobilier, de maisons, de voitures, et m\u00eame d\u2019un terrain de football. Ils ont aussi expliqu\u00e9 comment ces objets \u00e9taient importants dans l\u2019id\u00e9e d\u2019accueillir un invit\u00e9. Les b\u00e9n\u00e9voles et les adolescents ont \u00e9t\u00e9 alors s\u00e9par\u00e9s en deux groupes pour une deuxi\u00e8me activit\u00e9, o\u00f9 ils se sont affront\u00e9s dans diff\u00e9rents jeux sportifs orient\u00e9s vers le travail d\u2019\u00e9quipe. Cela leur a donn\u00e9 l\u2019opportunit\u00e9 de d\u00e9montrer leurs talents de sportifs.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>\n<p><a href=\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/image-5.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3756\" src=\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/image-5-300x200.png\" alt=\"image\" width=\"300\" height=\"200\"><\/a><\/p>\n<p>Cette journ\u00e9e \u00e0 \u00e9t\u00e9 un \u00e9norme succ\u00e8s, et ce d\u00e8s le d\u00e9but des activit\u00e9s, puisque chaque participant s\u2019est investi avec grand enthousiasme et a d\u00e9velopp\u00e9 un esprit d\u2019\u00e9quipe avec chacun des autres participants.<\/p>\n<p>Face \u00e0 la crise des migrants en Europe, des ONG comme SB OverSeas r\u00e9solvent les plus gros probl\u00e8mes de la soci\u00e9t\u00e9 et \u00e9tablissent des programmes d\u2019int\u00e9gration durable pour les r\u00e9fugi\u00e9es. Le r\u00e9seau d\u2019employ\u00e9s qualifi\u00e9s de PwC dans le monde est engag\u00e9 \u00e0 supporter ces initiatives, pour qu\u2019ils puissent \u00eatre \u00e0 l\u2019origine des changements proactifs qu\u2019ils veulent voir survenir dans la soci\u00e9t\u00e9. Ensemble, les ONG et les entreprises priv\u00e9es peuvent apporter une contribution cruciale pour cr\u00e9er et maintenir un climat d\u2019acceptation et de tol\u00e9rance, pour r\u00e9soudre ces probl\u00e8mes soci\u00e9taux.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>",
        "protected": false
    },
    "excerpt": {
        "rendered": "<p>&nbsp; Un groupe d\u2019employ\u00e9s tr\u00e8s motiv\u00e9s de PricewaterhouseCoopers a propos\u00e9 d\u2019offrir de son temps lors d\u2019un dimanche apr\u00e8s-midi ensoleill\u00e9 pour faire du b\u00e9n\u00e9volat avec SB OverSeas et les jeunes r\u00e9fugi\u00e9s du centre d\u2019Uccle Croix-Rouge. Les employ\u00e9s de PwC de toute la Belgique sont venus avec les membres de leur famille pour prendre part aux activit\u00e9s [&hellip;]<\/p>",
        "protected": false
    },
    "author": 162,
    "featured_media": 3753,
    "comment_status": "open",
    "ping_status": "closed",
    "sticky": false,
    "template": "",
    "format": "standard",
    "meta": {
        "_et_pb_use_builder": "",
        "_et_pb_old_content": "",
        "_et_gb_content_width": "",
        "footnotes": ""
    },
    "categories": [
        88,
        90,
        92,
        45
    ],
    "tags": [],
    "class_list": [
        "post-3752",
        "post",
        "type-post",
        "status-publish",
        "format-standard",
        "has-post-thumbnail",
        "hentry",
        "category-communiques-de-presse",
        "category-fr-evenements",
        "category-projets",
        "category-sb-espoir"
    ],
    "yoast_head": "<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SB OVERSEAS ET LES EMPLOY\u00c9S DE PWC FONT LA DIFF\u00c9RENCE POUR LES JEUNES R\u00c9FUGI\u00c9S DE BRUXELLES - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sboverseas.org\/en\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SB OVERSEAS ET LES EMPLOY\u00c9S DE PWC FONT LA DIFF\u00c9RENCE POUR LES JEUNES R\u00c9FUGI\u00c9S DE BRUXELLES - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Un groupe d\u2019employ\u00e9s tr\u00e8s motiv\u00e9s de PricewaterhouseCoopers a propos\u00e9 d\u2019offrir de son temps lors d\u2019un dimanche apr\u00e8s-midi ensoleill\u00e9 pour faire du b\u00e9n\u00e9volat avec SB OverSeas et les jeunes r\u00e9fugi\u00e9s du centre d\u2019Uccle Croix-Rouge. Les employ\u00e9s de PwC de toute la Belgique sont venus avec les membres de leur famille pour prendre part aux activit\u00e9s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sboverseas.org\/en\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/\" \/>\n<meta property=\"og:site_name\" content=\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-15T19:18:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/image-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sboverseas.org\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/\",\"url\":\"https:\/\/sboverseas.org\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/\",\"name\":\"SB OVERSEAS ET LES EMPLOY\u00c9S DE PWC FONT LA DIFF\u00c9RENCE POUR LES JEUNES R\u00c9FUGI\u00c9S DE BRUXELLES - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"isPartOf\":{\"@id\":\"https:\/\/sboverseas.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sboverseas.org\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sboverseas.org\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/image-2.png\",\"datePublished\":\"2017-05-15T19:18:24+00:00\",\"author\":{\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sboverseas.org\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sboverseas.org\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/#primaryimage\",\"url\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/image-2.png\",\"contentUrl\":\"https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/image-2.png\",\"width\":770,\"height\":400},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sboverseas.org\/#website\",\"url\":\"https:\/\/sboverseas.org\/\",\"name\":\"SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire\",\"description\":\"Give Hope\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sboverseas.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sboverseas.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sboverseas.org\"],\"url\":\"https:\/\/sboverseas.org\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->",
    "yoast_head_json": {
        "title": "SB OVERSEAS ET LES EMPLOY\u00c9S DE PWC FONT LA DIFF\u00c9RENCE POUR LES JEUNES R\u00c9FUGI\u00c9S DE BRUXELLES - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire",
        "robots": {
            "index": "index",
            "follow": "follow",
            "max-snippet": "max-snippet:-1",
            "max-image-preview": "max-image-preview:large",
            "max-video-preview": "max-video-preview:-1"
        },
        "canonical": "https:\/\/sboverseas.org\/en\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/",
        "og_locale": "en_US",
        "og_type": "article",
        "og_title": "SB OVERSEAS ET LES EMPLOY\u00c9S DE PWC FONT LA DIFF\u00c9RENCE POUR LES JEUNES R\u00c9FUGI\u00c9S DE BRUXELLES - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire",
        "og_description": "&nbsp; Un groupe d\u2019employ\u00e9s tr\u00e8s motiv\u00e9s de PricewaterhouseCoopers a propos\u00e9 d\u2019offrir de son temps lors d\u2019un dimanche apr\u00e8s-midi ensoleill\u00e9 pour faire du b\u00e9n\u00e9volat avec SB OverSeas et les jeunes r\u00e9fugi\u00e9s du centre d\u2019Uccle Croix-Rouge. Les employ\u00e9s de PwC de toute la Belgique sont venus avec les membres de leur famille pour prendre part aux activit\u00e9s [&hellip;]",
        "og_url": "https:\/\/sboverseas.org\/en\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/",
        "og_site_name": "SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire",
        "article_published_time": "2017-05-15T19:18:24+00:00",
        "og_image": [
            {
                "width": 770,
                "height": 400,
                "url": "https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/image-2.png",
                "type": "image\/png"
            }
        ],
        "author": "admin",
        "twitter_card": "summary_large_image",
        "twitter_misc": {
            "Written by": "admin",
            "Est. reading time": "3 minutes"
        },
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "WebPage",
                    "@id": "https:\/\/sboverseas.org\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/",
                    "url": "https:\/\/sboverseas.org\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/",
                    "name": "SB OVERSEAS ET LES EMPLOY\u00c9S DE PWC FONT LA DIFF\u00c9RENCE POUR LES JEUNES R\u00c9FUGI\u00c9S DE BRUXELLES - SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire",
                    "isPartOf": {
                        "@id": "https:\/\/sboverseas.org\/#website"
                    },
                    "primaryImageOfPage": {
                        "@id": "https:\/\/sboverseas.org\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/#primaryimage"
                    },
                    "image": {
                        "@id": "https:\/\/sboverseas.org\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/#primaryimage"
                    },
                    "thumbnailUrl": "https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/image-2.png",
                    "datePublished": "2017-05-15T19:18:24+00:00",
                    "author": {
                        "@id": "https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d"
                    },
                    "inLanguage": "en-US",
                    "potentialAction": [
                        {
                            "@type": "ReadAction",
                            "target": [
                                "https:\/\/sboverseas.org\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/"
                            ]
                        }
                    ]
                },
                {
                    "@type": "ImageObject",
                    "inLanguage": "en-US",
                    "@id": "https:\/\/sboverseas.org\/sb-overseas-et-les-employes-de-pwc-font-la-difference-pour-les-jeunes-refugies-de-bruxelles\/#primaryimage",
                    "url": "https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/image-2.png",
                    "contentUrl": "https:\/\/sboverseas.org\/wp-content\/uploads\/2018\/07\/image-2.png",
                    "width": 770,
                    "height": 400
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/sboverseas.org\/#website",
                    "url": "https:\/\/sboverseas.org\/",
                    "name": "SBO - D\u00e9veloppement Durable &amp; Aide Humanitaire",
                    "description": "Give Hope",
                    "potentialAction": [
                        {
                            "@type": "SearchAction",
                            "target": {
                                "@type": "EntryPoint",
                                "urlTemplate": "https:\/\/sboverseas.org\/?s={search_term_string}"
                            },
                            "query-input": {
                                "@type": "PropertyValueSpecification",
                                "valueRequired": true,
                                "valueName": "search_term_string"
                            }
                        }
                    ],
                    "inLanguage": "en-US"
                },
                {
                    "@type": "Person",
                    "@id": "https:\/\/sboverseas.org\/#\/schema\/person\/798cbdc4f79ea3b1324971e880f7317d",
                    "name": "admin",
                    "image": {
                        "@type": "ImageObject",
                        "inLanguage": "en-US",
                        "@id": "https:\/\/sboverseas.org\/#\/schema\/person\/image\/",
                        "url": "https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g",
                        "contentUrl": "https:\/\/secure.gravatar.com\/avatar\/63861348f82d85942901b19542593f8585b87f5bd53fd3c961e6defc2462d6ac?s=96&d=mm&r=g",
                        "caption": "admin"
                    },
                    "sameAs": [
                        "https:\/\/sboverseas.org"
                    ],
                    "url": "https:\/\/sboverseas.org\/en\/author\/admin\/"
                }
            ]
        }
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/posts\/3752",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/posts"
            }
        ],
        "about": [
            {
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/types\/post"
            }
        ],
        "author": [
            {
                "embeddable": true,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/users\/162"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/comments?post=3752"
            }
        ],
        "version-history": [
            {
                "count": 0,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/posts\/3752\/revisions"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/media\/3753"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/media?parent=3752"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "category",
                "embeddable": true,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/categories?post=3752"
            },
            {
                "taxonomy": "post_tag",
                "embeddable": true,
                "href": "https:\/\/sboverseas.org\/en\/wp-json\/wp\/v2\/tags?post=3752"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}